{"id":72646,"date":"2016-06-30T18:49:09","date_gmt":"2016-06-30T16:49:09","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=72646"},"modified":"2025-08-30T10:03:35","modified_gmt":"2025-08-30T08:03:35","slug":"elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/","title":{"rendered":"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini"},"content":{"rendered":"<div>\n<div>\n<p><strong>Elicriso (Helichrysum italicum) Estratto Integrale\u00a0Liquido analcoolico 200 ml &#8211; dr. Giorgini<\/strong><\/p>\n<p>L\u2019elicriso svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit\u00e0 del microcircolo e promuove la funzione digestiva ed epatica.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 10 ml diluiti in un bicchiere d\u2019acqua, una o due volte al giorno in qualunque momento (da 10 a 20 ml al giorno).<\/p>\n<p>Se desiderato, la dose giornaliera pu\u00f2 essere diluita in una bottiglia d\u2019acqua da consumare nell\u2019arco della giornata.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n<p>Conservare il prodotto fuori dal frigorifero anche dopo l&#8217;apertura.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicerina vegetale bidistillata, acqua pura, elicriso (Helichrysum italicum) erba con fiori E.I.L.<\/p>\n<p>E.I.L= Estratto integrale liquido.<\/p>\n<p><strong>Non contiene alcool, conservanti, coloranti, aromi ed edulcoranti di sintesi.<\/strong><\/p>\n<p><strong>Prodotto adatto ai vegani.<\/strong><\/p>\n<p><strong>Naturale caratteristica distintiva: sapore leggermente amaro e pungente<\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Elicriso (Helichrysum italicum) Estratto Integrale\u00a0Liquido analcoolico 200 ml &#8211; dr. Giorgini L\u2019elicriso svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit\u00e0 del microcircolo e promuove la funzione digestiva ed epatica. Consigli d&#8217;uso Si consiglia l\u2019assunzione di 10 ml diluiti&#8230;<\/p>\n","protected":false},"featured_media":120046,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[10371],"product_tag":[14752,11049,10705,11334,10856,16069,12235,14754,12102],"giftcard-category":[],"class_list":{"0":"post-72646","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-estratti-integrali","8":"product_tag-analcoolica","9":"product_tag-calendula","10":"product_tag-echinacea","11":"product_tag-elicriso","12":"product_tag-estratto","13":"product_tag-integrale","14":"product_tag-lapacho","15":"product_tag-tmg","16":"product_tag-totale","17":"pa_formato-200-ml","18":"pa_linea-estratti-integrali","19":"pa_marca-dr-giorgini","20":"pa_tipologia-liquido-analcolico","22":"first","23":"instock","24":"sale","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-30T08:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/\",\"name\":\"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg\",\"datePublished\":\"2016-06-30T16:49:09+00:00\",\"dateModified\":\"2025-08-30T08:03:35+00:00\",\"description\":\"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","description":"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/","og_locale":"it_IT","og_type":"article","og_title":"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","og_description":"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-08-30T08:03:35+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/","name":"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg","datePublished":"2016-06-30T16:49:09+00:00","dateModified":"2025-08-30T08:03:35+00:00","description":"Svolge un effetto balsamico utile per il benessere di naso e gola, favorisce la funzionalit? del microcircolo e promuove la funzione digestiva ed epatica.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/06\/00009277-elicriso-integrale200.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/elicriso-estratto-integrale-analcoolico-200ml-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Elicriso Estratto Integrale analcoolico 200ml dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/72646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/120046"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=72646"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=72646"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=72646"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=72646"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=72646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}