{"id":69450,"date":"2015-04-02T16:10:36","date_gmt":"2015-04-02T14:10:36","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=69450"},"modified":"2025-08-30T09:38:53","modified_gmt":"2025-08-30T07:38:53","slug":"drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/","title":{"rendered":"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico"},"content":{"rendered":"<p><strong>Drenamix 100ml analcolico &#8211; dr. Giorgini<\/strong><\/p>\n<p>Gemmoderivato + Tintura Madre<\/p>\n<p>La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicerina vegetale bidistillata, acqua pura, betulla bianca (Betula alba, sinonimi Betula pubescens, Betula verrucosa o Betula pendula) foglie (10%); tessuti meristematici freschi (10%): betulla bianca (Betula alba, sinonimi Betula pubescens, Betula verrucosa o Betula pendula) linfa, faggio (Fagus sylvatica) gemme, ginepro (Juniperus communis) giovani getti, erica o brugo (Calluna vulgaris) giovani getti, mirtillo nero (Vaccinium myrtillus) giovani getti, mirtillo rosso (Vaccinium vitis-idaea) giovani getti.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione delle dosi riportate di seguito, da una a tre volte al giorno in qualunque momento:<\/p>\n<p>1,4 ml per bambini da 1 a 3 anni;<br \/>\n2 ml per bambini da 4 a 6 anni;<br \/>\n3,5 ml per bambini da 7 a 10 anni;<br \/>\n5 ml per adulti.<\/p>\n<p>Diluire il prodotto in acqua calda o fredda.<\/p>\n<p>Se desiderato, le tre dosi possono essere assunte anche in un\u2019unica soluzione.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n<p><strong>Note sulla preparazione<\/strong><\/p>\n<p>I prodotti della Linea Mix contengono <strong>due prodotti in uno.<\/strong><\/p>\n<p>Infatti sono costituiti da una miscela concentrata di Gemmoderivati arricchiti con una Tintura Madre ad azione sinergica.<\/p>\n<p>I Gemmoderivati del Dr. Giorgini sono ottenuti utilizzando <strong>solo tessuti meristematici freschi<\/strong>, cio\u00e8 tessuti embrionali in via di accrescimento.<\/p>\n<p>Questi vengono raccolti in primavera e lavorati nella stessa giornata per mantenere inalterata la loro freschezza.<\/p>\n<p>Lo speciale metodo di<strong> lavorazione a freddo<\/strong> permette di estrarre e preservare integri tutti i principi attivi e nutritivi presenti nei tessuti embrionali delle piante.<\/p>\n<p>La Tintura Madre, preparata con il metodo inventato dal Dr. Giorgini, offre al Consumatore un estratto contenente l\u2019intero fitocomplesso della pianta.<\/p>\n<p>Tutti i prodotti della Linea Mix sono <strong>naturali al 100% e non contengono: zuccheri aggiunti, alcool, conservanti, aromi ed edulcoranti artificiali.<\/strong><\/p>\n<p>I prodotti della Linea Mix sono pi\u00f9 concentrati dei comuni Gemmoderivati o delle Tinture Madri, infatti hanno un rapporto di <strong>estrazione fi nale di 1:5, cio\u00e8 da 1 kg di piante si ottengono 5 litri di prodotto concentrato!<\/strong><\/p>\n<p>Inoltre, <strong>sono analcoolici<\/strong> (senza alcool) e dal sapore gradevole <strong>adatto anche ai bambini.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drenamix 100ml analcolico &#8211; dr. Giorgini Gemmoderivato + Tintura Madre La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo. Ingredienti Glicerina vegetale bidistillata, acqua pura, betulla bianca (Betula alba, sinonimi Betula pubescens, Betula verrucosa&#8230;<\/p>\n","protected":false},"featured_media":121143,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46266,10363,9867],"product_tag":[14956,12312,19375,17378,15596,12309,10952,10519],"giftcard-category":[],"class_list":{"0":"post-69450","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-apparato-urinario","8":"product_cat-linea-mix","9":"product_cat-drenaggio-e-depurazione","10":"product_tag-analcolico","11":"product_tag-dr","12":"product_tag-dr-giorgini","13":"product_tag-drenamix","14":"product_tag-essenzialvis","15":"product_tag-giorgini","16":"product_tag-gr","17":"product_tag-tav","18":"pa_formato-100-ml","19":"pa_linea-linea-mix","20":"pa_marca-dr-giorgini","21":"pa_tipologia-liquido-analcolico","23":"first","24":"instock","25":"sale","26":"taxable","27":"shipping-taxable","28":"purchasable","29":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-30T07:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/\",\"name\":\"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg\",\"datePublished\":\"2015-04-02T14:10:36+00:00\",\"dateModified\":\"2025-08-30T07:38:53+00:00\",\"description\":\"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra","description":"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/","og_locale":"it_IT","og_type":"article","og_title":"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra","og_description":"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-08-30T07:38:53+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/","name":"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg","datePublished":"2015-04-02T14:10:36+00:00","dateModified":"2025-08-30T07:38:53+00:00","description":"La betulla favorisce il drenaggio dei liquidi corporei, mantiene la funzionalit\u00e0 delle vie urinarie e promuove le funzioni depurative dell\u2019organismo.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2015\/04\/00009896-drenamix100.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/drenamix-100ml-favorisce-il-drenaggio-dei-liquidi-corporei-analcolico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Drenamix 100ml favorisce il drenaggio dei liquidi corporei. Analcolico"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/69450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/121143"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=69450"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=69450"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=69450"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=69450"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=69450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}