{"id":67838,"date":"2013-11-28T00:00:00","date_gmt":"2013-11-27T23:00:00","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=67838"},"modified":"2025-09-26T11:51:51","modified_gmt":"2025-09-26T09:51:51","slug":"gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/","title":{"rendered":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini"},"content":{"rendered":"<p><strong>Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml &#8211; dr.Giorgini<\/strong><\/p>\n<p>Gemmoderivato concentrato di Salice bianco (Salix alba)<\/p>\n<p><strong>Ingredienti<\/strong><br \/>\nGlicerina vegetale bidistillata, acqua pura, Salice bianco (Salix alba) gemme fresche (10%).<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><br \/>\nSi consiglia l\u2019assunzione delle dosi riportate di seguito, da una a tre volte al giorno in qualunque momento:<br \/>\n\u2022 1,4 ml per bambini da 1 a 3 anni;<br \/>\n\u2022 2 ml per bambini da 4 a 6 anni;<br \/>\n\u2022 3,5 ml per bambini da 7 a 10 anni;<br \/>\n\u2022 5 ml per adulti.<br \/>\nDiluire il prodotto in acqua calda o fredda.<\/p>\n<p>Se desiderato, le tre dosi possono essere assunte anche in un\u2019unica soluzione.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml &#8211; dr.Giorgini Gemmoderivato concentrato di Salice bianco (Salix alba) Ingredienti Glicerina vegetale bidistillata, acqua pura, Salice bianco (Salix alba) gemme fresche (10%). Consigli d&#8217;uso Si consiglia l\u2019assunzione delle dosi riportate di seguito, da una a tre volte&#8230;<\/p>\n","protected":false},"featured_media":122525,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[45107,46263,10179,49561],"product_tag":[15382,14956,10590,16978,11694],"giftcard-category":[],"class_list":{"0":"post-67838","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-gemmoderivati-mg","8":"product_cat-dr-apparato-muscoloscheletrico","9":"product_cat-gemmoderivati-gemmo-10-piu","10":"product_cat-singoli-liquidi","11":"product_tag-500ml","12":"product_tag-analcolico","13":"product_tag-bianco","14":"product_tag-gemmo","15":"product_tag-salice","16":"pa_formato-500-ml","17":"pa_linea-gemmo-10-gemmoderivati-concentrati-2","18":"pa_marca-dr-giorgini","20":"first","21":"instock","22":"sale","23":"taxable","24":"shipping-taxable","25":"purchasable","26":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T09:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/\",\"name\":\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg\",\"datePublished\":\"2013-11-27T23:00:00+00:00\",\"dateModified\":\"2025-09-26T09:51:51+00:00\",\"description\":\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra","description":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/","og_locale":"it_IT","og_type":"article","og_title":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra","og_description":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-26T09:51:51+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/","name":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg","datePublished":"2013-11-27T23:00:00+00:00","dateModified":"2025-09-26T09:51:51+00:00","description":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato analcolico Dr. Giorgini. Senza zucchero, coloranti, edulcoranti, conservanti di sintesi e alcool.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/11\/00010677_GEMMO10_Salix-Alba_500ml_salice_bianco_gemmoderivato.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/gemmo-10-salice-bianco-salix-alba-gemmoderivato-500ml-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Gemmo 10+ Salice bianco (Salix alba) gemmoderivato 500ml dr.Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/67838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/122525"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=67838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=67838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=67838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=67838"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=67838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}