{"id":64854,"date":"2013-05-11T00:00:00","date_gmt":"2013-05-11T00:00:00","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=64854"},"modified":"2026-01-30T12:26:50","modified_gmt":"2026-01-30T11:26:50","slug":"inositolo-supremo-140-pastiglie-funzione-epatica","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/","title":{"rendered":"Inositolo Supremo\u00a0140 pastiglie Funzione epatica"},"content":{"rendered":"<p><strong>Inositolo Supremo\u00a0140 pastiglie &#8211; dr. Giorgini<\/strong><\/p>\n<p>Integratore alimentare a base di inositolo, erbe, sali minerali e vitamine.<\/p>\n<p>Il carciofo favorisce le funzioni depurative dell\u2019organismo e, insieme al rosmarino, promuove la funzione epatica e svolge una benefica azione antiossidante.<\/p>\n<p>Selenio e vitamine B2, C, ed E contribuiscono alla protezione delle cellule dallo stress ossidativo.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 5 pastiglie una o due volte al giorno in qualunque momento (da 5 a 10 pastiglie al giorno). Richiudere accuratamente dopo l&#8217;utilizzo.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Mio-Inositolo di origine vegetale (estratto da semi di mais), carciofo (Cynara scolymus) foglie E.S. (titolato al 5% in acido clorogenico), cellulosa microcristallina\u00b0, gomma arabica\u00b0, gelatina alimentare, rosa canina (Rosa canina) frutti E.S. (titolato al 70% in vitamina C), silicio biossido\u00b0\u00b0, vitamina E di origine vegetale (acetato di D-\u03b1-tocoferile), magnesio stearato di origine vegetale\u00b0\u00b0, acerola (Malpighia glabra) frutti E.S. (titolato al 50% in vitamina C), rosmarino (Rosmarinus officinalis) sommit\u00e0 fiorite O.E., vitamina B3 (nicotinamide), vitamina B5 (pantotenato di calcio), vitamina B6 (piridossina cloridrato), vitamina B1 (tiamina cloridrato), vitamina B2 (riboflavina), cromo picolinato, acido folico, sodio selenito, biotina, vitamina B12 (cianocobalamina). \u00b0Agente di carica. \u00b0\u00b0Antiagglomerante.<br \/>\nE.S.= Estratto secco. O.E.= Olio essenziale (Aetheroleum). NRV= Valore nutritivo di riferimento.<\/p>\n<p><strong>Non contiene conservanti, coloranti, aromi ed edulcoranti di sintesi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inositolo Supremo\u00a0140 pastiglie &#8211; dr. Giorgini Integratore alimentare a base di inositolo, erbe, sali minerali e vitamine. Il carciofo favorisce le funzioni depurative dell\u2019organismo e, insieme al rosmarino, promuove la funzione epatica e svolge una benefica azione antiossidante. Selenio e vitamine B2, C, ed E&#8230;<\/p>\n","protected":false},"featured_media":119257,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46275,10163],"product_tag":[16210,14699,13565],"giftcard-category":[],"class_list":{"0":"post-64854","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-vitamine","8":"product_cat-linea-oro-classica","9":"product_tag-inositolo","10":"product_tag-pastiglie","11":"product_tag-supremo","12":"pa_formato-140-pastiglie","13":"pa_linea-linea-oro","14":"pa_marca-dr-giorgini","15":"pa_tipologia-compresse","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:26:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/\",\"name\":\"Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg\",\"datePublished\":\"2013-05-11T00:00:00+00:00\",\"dateModified\":\"2026-01-30T11:26:50+00:00\",\"description\":\"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inositolo Supremo\u00a0140 pastiglie Funzione epatica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra","description":"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/","og_locale":"it_IT","og_type":"article","og_title":"Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra","og_description":"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:26:50+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/","name":"Inositolo Supremo\u00a0140 pastiglie Funzione epatica - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg","datePublished":"2013-05-11T00:00:00+00:00","dateModified":"2026-01-30T11:26:50+00:00","description":"Favorisce le funzioni depurative dell\u2019organismo, promuove la funzione epatica e svolge una benefica azione antiossidante.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009763-inositolo-supremo-140-pastiglie.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/inositolo-supremo-140-pastiglie-funzione-epatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Inositolo Supremo\u00a0140 pastiglie Funzione epatica"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/64854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/119257"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=64854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=64854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=64854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=64854"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=64854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}