{"id":62126,"date":"2013-05-11T00:00:00","date_gmt":"2013-05-10T22:00:00","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=62126"},"modified":"2026-02-26T16:24:43","modified_gmt":"2026-02-26T15:24:43","slug":"biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/","title":{"rendered":"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie &#8211; Dr. Giorgini"},"content":{"rendered":"<p><strong>Biliaris-T 60 pastiglie per la funzionalit\u00e0 epatica- Dr. Giorgini<\/strong><\/p>\n<p>Boldo, carciofo, crespino e tarassaco promuovono la funzionalit\u00e0 epatica mentre cicoria e fumaria favoriscono anche quella delle vie biliari.<\/p>\n<p>Inoltre, tutte le piante contenute nel prodotto agiscono facilitando la funzione digestiva.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 6 pastiglie una o due volte al giorno in qualunque momento (da 6 a 12 pastiglie al giorno).\u00a0Suggerito 20 minuti prima di mangiare.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicina, boldo (Peumus boldus) foglie E.I.S., taurina, cellulosa microcristallina\u00b0, gomma arabica\u00b0, carciofo (Cynara scolymus) foglie E.I.S., crespino (Berberis vulgaris) cortecce delle radici E.I.S., fumaria (Fumaria officinalis) erba con fiori E.I.S., tarassaco (Taraxacum officinale) radici E.I.S., cicoria (Cichorium intybus) radici E.I.S., rafano nero (Raphanus sativus var. niger) radici E.I.S., silicio biossido\u00b0\u00b0, magnesio stearato di origine vegetale\u00b0\u00b0.<br \/>\n\u00b0Agente di carica.<br \/>\n\u00b0\u00b0Antiagglomerante.<\/p>\n<p><strong>Non contiene conservanti, coloranti, aromi ed edulcoranti di sintesi.<\/strong><\/p>\n<p><strong>Prodotto adatto ai vegani, senza glutine (Glutine &lt;0,002%).<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Biliaris-T 60 pastiglie per la funzionalit\u00e0 epatica- Dr. Giorgini Boldo, carciofo, crespino e tarassaco promuovono la funzionalit\u00e0 epatica mentre cicoria e fumaria favoriscono anche quella delle vie biliari. Inoltre, tutte le piante contenute nel prodotto agiscono facilitando la funzione digestiva. Consigli d&#8217;uso Si consiglia l\u2019assunzione&#8230;<\/p>\n","protected":false},"featured_media":110112,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46262,10163],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-62126","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-apparato-digerente","8":"product_cat-linea-oro-classica","9":"pa_formato-60-pastiglie","10":"pa_linea-linea-oro","11":"pa_marca-dr-giorgini","12":"pa_tipologia-compresse","14":"first","15":"instock","16":"sale","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T15:24:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/\",\"name\":\"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg\",\"datePublished\":\"2013-05-10T22:00:00+00:00\",\"dateModified\":\"2026-02-26T15:24:43+00:00\",\"description\":\"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie &#8211; Dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra","description":"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/","og_locale":"it_IT","og_type":"article","og_title":"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra","og_description":"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-02-26T15:24:43+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/","name":"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie - Dr. Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg","datePublished":"2013-05-10T22:00:00+00:00","dateModified":"2026-02-26T15:24:43+00:00","description":"Biliaris promuove la funzionalit\u00e0 epatica e quella delle vie biliari. Inoltre agisce facilitando la funzione digestiva. Non serve conservare in frigorifero.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009659.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biliaris-t-per-la-funzionalita-epatica-60-pastiglie-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Biliaris-T per la funzionalit\u00e0 epatica 60 pastiglie &#8211; Dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/62126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/110112"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=62126"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=62126"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=62126"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=62126"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=62126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}