{"id":59838,"date":"2011-07-29T17:27:46","date_gmt":"2011-07-29T15:27:46","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=59838"},"modified":"2025-09-14T17:50:26","modified_gmt":"2025-09-14T15:50:26","slug":"willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/","title":{"rendered":"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita"},"content":{"rendered":"<p data-start=\"0\" data-end=\"100\"><strong data-start=\"0\" data-end=\"98\">Willow rimedio di Bach n\u00b0 38 &#8211; Per chi si sente vittima delle circostanze e provato dalla vita<\/strong><\/p>\n<p data-start=\"102\" data-end=\"171\"><strong data-start=\"102\" data-end=\"153\">Willow (Salix vitellina) &#8211; rimedio di Bach n\u00b038<\/strong><br data-start=\"153\" data-end=\"156\" \/>Flacone 10 ml<\/p>\n<p data-start=\"173\" data-end=\"272\"><em data-start=\"173\" data-end=\"270\">&#8220;Per coloro che si sentono vittime della vita, amareggiati e risentiti, incapaci di perdonare.&#8221;<\/em><\/p>\n<p data-start=\"274\" data-end=\"599\">Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono un risentimento profondo e difficolt\u00e0 nell\u2019accettare i propri fallimenti. Questo fiore aiuta a superare il senso di vittimismo e a trasformare il risentimento in un atteggiamento pi\u00f9 positivo e proattivo.<\/p>\n<p data-start=\"601\" data-end=\"940\">Le persone che beneficiano di Willow possono spesso trovarsi in una spirale di amarezza, pensando che le cose non vanno mai come dovrebbero, e riversando la responsabilit\u00e0 sulle situazioni e sugli altri. Con l&#8217;uso di Willow, si sviluppa una maggiore comprensione e gratitudine, aiutando a superare il malcontento e a trovare la serenit\u00e0.<\/p>\n<p data-start=\"942\" data-end=\"1111\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"942\" data-end=\"956\">Modo d&#8217;uso<\/strong><\/p>\n<p data-start=\"942\" data-end=\"1111\" data-is-last-node=\"\" data-is-only-node=\"\">Secondo il Dr. Bach, i rimedi floreali vanno assunti nella dose di 4 gocce alla volta, 4 volte al giorno, direttamente in bocca o diluiti in poca acqua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willow rimedio di Bach n\u00b0 38 &#8211; Per chi si sente vittima delle circostanze e provato dalla vita Willow (Salix vitellina) &#8211; rimedio di Bach n\u00b038Flacone 10 ml &#8220;Per coloro che si sentono vittime della vita, amareggiati e risentiti, incapaci di perdonare.&#8221; Willow \u00e8 il&#8230;<\/p>\n","protected":false},"featured_media":54531,"template":"","meta":{"_acf_changed":false},"product_brand":[9639],"product_cat":[45104],"product_tag":[12394,11016,12397,12395,12398,14248,14247],"giftcard-category":[],"class_list":{"0":"post-59838","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-laboratorio-erboristico-di-leo","7":"product_cat-fiori-di-bach","8":"product_tag-bach","9":"product_tag-fiori","10":"product_tag-flowers","11":"product_tag-healing","12":"product_tag-herbs","13":"product_tag-n-38","14":"product_tag-willow","15":"pa_formato-10-ml","16":"pa_linea-fiori-bach-flowers","17":"pa_marca-di-leo","18":"pa_tipologia-gocce","19":"pa_tipologia-liquido-alcolico","21":"first","22":"instock","23":"sale","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-14T15:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/\",\"name\":\"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg\",\"datePublished\":\"2011-07-29T15:27:46+00:00\",\"dateModified\":\"2025-09-14T15:50:26+00:00\",\"description\":\"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg\",\"width\":\"500\",\"height\":\"640\",\"caption\":\"CRAB APPLE 10 ML - FIORI DI BACH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra","description":"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/","og_locale":"it_IT","og_type":"article","og_title":"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra","og_description":"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-14T15:50:26+00:00","og_image":[{"width":500,"height":640,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/","name":"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg","datePublished":"2011-07-29T15:27:46+00:00","dateModified":"2025-09-14T15:50:26+00:00","description":"Willow \u00e8 il rimedio di Bach per coloro che si sentono ingiustamente trattati dalle circostanze della vita, che nutrono difficolt\u00e0 nell\u2019accettare i fallimenti","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-_BACHDILEO.jpg","width":"500","height":"640","caption":"CRAB APPLE 10 ML - FIORI DI BACH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/willow-rimedio-bach-flowers-n38-per-chi-si-sente-vittima-delle-circostanze-e-provato-dalla-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Willow rimedio Bach Flowers n\u00b038 Per chi si sente vittima delle circostanze e provato dalla vita"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/59838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/54531"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=59838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=59838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=59838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=59838"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=59838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}