{"id":52154,"date":"2008-05-09T10:45:07","date_gmt":"2008-05-09T10:45:07","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=52154"},"modified":"2025-09-10T18:55:12","modified_gmt":"2025-09-10T16:55:12","slug":"tonico-viso-per-pelli-miste-e-grasse-l-erbolario","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/","title":{"rendered":"Tonico viso per pelli miste e grasse L&#8217;Erbolario"},"content":{"rendered":"<p><strong>Acqua Aromatica per Pelli Miste e Grasse &#8211; L&#8217;Erbolario<\/strong><br \/>\nTonico astringente al Rosmarino per pelli miste e grasse<br \/>\nFormato: 200 ml<br \/>\n<strong>Descrizione<\/strong><br \/>\nQuesto tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.<br \/>\n<strong>Consigli d&#8217;uso<\/strong><br \/>\nDopo la detersione del mattino e della sera, dosare il prodotto su un dischetto di cotone e picchiettare delicatamente su Zona T, collo e decollet\u00e9. Lasciar asciugare prima di procedere ai trattamenti abituali. Evitare il contatto diretto con gli occhi.<br \/>\n<strong>Sostanze funzionali<\/strong><br \/>\nAcqua distillata di Rosmarino, complesso idratante cutaneo NMF<\/p>\n<p><strong>COSA SAPERE IN PIU&#8217;<\/strong><\/p>\n<p><strong>100% Made in Italy<\/strong><br \/>\nOgni fase della nostra attivit\u00e0, dalla formulazione al controllo qualit\u00e0, dalla preparazione del semilavorato al confezionamento, viene attuata da sempre nel nostro sito produttivo di Lodi: noi non abbiamo delocalizzato alcuna fase produttiva in paesi terzi, men che meno in quelli nei quali i diritti umani e i diritti fondamentali dei lavoratori sono calpestati. I nostri fitocosmetici sono orgogliosi di potersi dire 100% MADE IN ITALY!<br \/>\n<strong>7 Metalli testati<\/strong><br \/>\nMonitoraggio del contenuto di 7 metalli per minimizzare i rischi di allergia: *(Nichel, Piombo, Arsenico, Cadmio, Mercurio, Antimonio e Cromo) e salvaguardare cos\u00ec anche le pelli pi\u00f9 sensibili. Ogni lotto di produzione \u00e8 rigorosamente controllato per garantire un contenuto di ogni singolo metallo inferiore a 0.00005% (limite di rilevabilit\u00e0 strumentale).<br \/>\n<strong>Da sempre amici degli animali<\/strong><br \/>\nAderiamo allo \u201cStandard Internazionale Stop ai Test su Animali\u201d; garantito da LAV (Lega Anti Vivisezione). Fin dalla sua fondazione nel 1978 L&#8217;Erbolario ha seguito la politica di non ricorrere a test su animali e dal 2006, dopo che le normative europee hanno iniziato a limitare e poi hanno man mano proibito il ricorso ai test su animali per fini cosmetici, ha aderito allo Standard. www.lav.it<br \/>\n<strong>Dermatologicamente Testato<\/strong><br \/>\nQuesto prodotto ha dimostrato di essere ottimamente tollerato dopo una rigorosa sperimentazione clinica finalizzata alla ricerca di eventuali potenzialit\u00e0 di irritazione e di allergogenesi. La valutazione delle ricerche \u00e8 stata effettuata presso il Dipartimento di Medicina interna e Terapia medica dell\u2019Universit\u00e0 degli Studi di Pavia.<br \/>\nImballo in Carta FSC\u00ae<br \/>\nLa confezione esterna cartacea di questo prodotto \u00e8 costituita esclusivamente carta certificata FSC\u00ae, secondo i rigorosi standardambientali e sociali del Forest Stewardship Concil\u00ae a supporto di una corretta e responsabile gestione delle risorse forestali<br \/>\n<strong>Senza ingredienti di derivazione animale<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acqua Aromatica per Pelli Miste e Grasse &#8211; L&#8217;Erbolario Tonico astringente al Rosmarino per pelli miste e grasse Formato: 200 ml Descrizione Questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere&#8230;<\/p>\n","protected":false},"featured_media":109415,"template":"","meta":{"_acf_changed":false},"product_brand":[9603],"product_cat":[45040],"product_tag":[10954,11358,11353,11029,11031,11033,10795,10985],"giftcard-category":[],"class_list":{"0":"post-52154","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbolario","7":"product_cat-viso","8":"product_tag-acqua","9":"product_tag-grasse","10":"product_tag-lerbolario","11":"product_tag-miste","12":"product_tag-pelli","13":"product_tag-rosmarino","14":"product_tag-tonico","15":"product_tag-viso","16":"pa_formato-200-ml","17":"pa_linea-profumazione-viso","18":"pa_marca-lerbolario","19":"pa_tipologia-tonico","21":"first","22":"instock","23":"sale","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tonico viso per pelli miste e grasse L&#039;Erbolario<\/title>\n<meta name=\"description\" content=\"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tonico viso per pelli miste e grasse L&#039;Erbolario\" \/>\n<meta property=\"og:description\" content=\"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T16:55:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"727\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/\",\"name\":\"Tonico viso per pelli miste e grasse L'Erbolario\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg\",\"datePublished\":\"2008-05-09T10:45:07+00:00\",\"dateModified\":\"2025-09-10T16:55:12+00:00\",\"description\":\"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg\",\"width\":727,\"height\":790},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tonico viso per pelli miste e grasse L&#8217;Erbolario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tonico viso per pelli miste e grasse L'Erbolario","description":"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/","og_locale":"it_IT","og_type":"article","og_title":"Tonico viso per pelli miste e grasse L'Erbolario","og_description":"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-10T16:55:12+00:00","og_image":[{"width":727,"height":790,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/","name":"Tonico viso per pelli miste e grasse L'Erbolario","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg","datePublished":"2008-05-09T10:45:07+00:00","dateModified":"2025-09-10T16:55:12+00:00","description":"Al Rosmarino questo tonico \u00e8 particolarmente indicato per le pelli grasse perch\u00e9, dopo la detersione, \u00e8 in grado di rimuovere le ultime impurit\u00e0 e richiudere delicatamente i pori dilatati, idratando la pelle del viso e mantenedola liscia e fresca.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001850-1.jpg","width":727,"height":790},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/tonico-viso-per-pelli-miste-e-grasse-l-erbolario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Tonico viso per pelli miste e grasse L&#8217;Erbolario"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/52154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/109415"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=52154"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=52154"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=52154"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=52154"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=52154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}