{"id":51926,"date":"2008-05-09T12:45:04","date_gmt":"2008-05-09T10:45:04","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=51926"},"modified":"2025-02-10T20:34:11","modified_gmt":"2025-02-10T19:34:11","slug":"basilico-foglie-in-taglio-tisana-ocimum-basilicum-l","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/","title":{"rendered":"Basilico foglie in taglio tisana (Ocimum basilicum L.)"},"content":{"rendered":"<p><strong>Foglie in Taglio Tisana di Basilico (Ocimum basilicum L.)<\/strong><\/p>\n<p>Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un&#8217;infusione delicata e ricca di benefici.<\/p>\n<p>Utilizzato nella tradizione erboristica per le sue propriet\u00e0 digestive e antinfiammatorie, il Basilico \u00e8 ideale per favorire la digestione e alleviare la sensazione di gonfiore.<\/p>\n<p>Inoltre, le sue propriet\u00e0 rilassanti e tonificanti lo rendono un ingrediente perfetto per tisane dal gusto fresco e riequilibrante.<\/p>\n<p>Lavorato in taglio tisana, il Basilico mantiene intatte le sue qualit\u00e0 naturali, offrendo un infuso che unisce gusto, freschezza e benessere.<\/p>\n<p>Perfetto per chi cerca un rimedio naturale per migliorare la digestione e godere di un momento di tranquillit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foglie in Taglio Tisana di Basilico (Ocimum basilicum L.) Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un&#8217;infusione delicata e ricca di benefici. Utilizzato nella tradizione erboristica per le sue&#8230;<\/p>\n","protected":false},"featured_media":50903,"template":"","meta":{"_acf_changed":false},"product_brand":[9617],"product_cat":[10051,10331],"product_tag":[11211,11212,20644,21103,11210],"giftcard-category":[],"class_list":{"0":"post-51926","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbamea","7":"product_cat-erbe-b","8":"product_cat-spezie-e-aromi-per-cucina","9":"product_tag-basilico","10":"product_tag-basilicum","11":"product_tag-foglie-2","12":"product_tag-gr-2","13":"product_tag-ocimum","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un&#039;infusione delicata e ricca di benefici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un&#039;infusione delicata e ricca di benefici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T19:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/\",\"name\":\"Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"datePublished\":\"2008-05-09T10:45:04+00:00\",\"dateModified\":\"2025-02-10T19:34:11+00:00\",\"description\":\"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un'infusione delicata e ricca di benefici.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"width\":350,\"height\":458,\"caption\":\"Erbe officinali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Basilico foglie in taglio tisana (Ocimum basilicum L.)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra","description":"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un'infusione delicata e ricca di benefici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/","og_locale":"it_IT","og_type":"article","og_title":"Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra","og_description":"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un'infusione delicata e ricca di benefici.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-02-10T19:34:11+00:00","og_image":[{"width":350,"height":458,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/","name":"Basilico foglie in taglio tisana (Ocimum basilicum L.) - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","datePublished":"2008-05-09T10:45:04+00:00","dateModified":"2025-02-10T19:34:11+00:00","description":"Le foglie di Basilico, provenienti dalla pianta Ocimum basilicum L., sono apprezzate per il loro aroma fresco e il sapore aromatico, che conferiscono un'infusione delicata e ricca di benefici.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","width":350,"height":458,"caption":"Erbe officinali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/basilico-foglie-in-taglio-tisana-ocimum-basilicum-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Basilico foglie in taglio tisana (Ocimum basilicum L.)"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/51926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/50903"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=51926"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=51926"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=51926"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=51926"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=51926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}