{"id":133581,"date":"2026-03-20T12:28:29","date_gmt":"2026-03-20T11:28:29","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=133581"},"modified":"2026-03-25T18:24:12","modified_gmt":"2026-03-25T17:24:12","slug":"bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/","title":{"rendered":"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify; mso-layout-grid-align: none;\"><i><span style=\"font-size: 9pt; color: #8d8026; font-family: Verdana; mso-bidi-font-family: GillSansStd-Italic;\"><!--?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/--><\/span><\/i><\/p>\n<p><strong>Bioflor new formula 30 capsule vegetali &#8211; Solgar.<\/strong><\/p>\n<p>Nuova Formula <strong>con 13 Ceppi<\/strong><\/p>\n<p>BIOFLOR \u00e8 un integratore alimentare formulato per un uso quotidiano a base di 13 ceppi di probiotici accuratamente selezionati per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale, garantendo una <strong>concentrazione totale di 10 miliardi di UFC* per capsula.<\/strong><\/p>\n<p>I probiotici favoriscono l\u2019equilibrio della flora intestinale.<\/p>\n<p>I ceppi probiotici presenti in BIOFLOR sono stati selezionati per la loro resistenza alle difficili condizioni del tratto gastro-intestinale, e sono conservati in un flacone appositamente progettato per preservare la stabilit\u00e0 e la vitalit\u00e0 dei microrganismi fino alla fine della durata di conservazione.<\/p>\n<p>Ideale anche in viaggio, BIOFLOR non richiede refrigerazione.<\/p>\n<p>*UFC=Unit\u00e0 Formanti Colonie (cellule vive).<\/p>\n<p><strong>Modo d&#8217;uso<\/strong><\/p>\n<p>Deglutire 1 capsula vegetale al giorno, con acqua, preferibilmente lontano dai pasti. Non superare la dose giornaliera raccomandata. Confezionato in flaconi da 30 capsule vegetali.<\/p>\n<p><strong>Naturalmente priva di lattosio e latto-derivati, senza glutine.<\/strong><\/p>\n<p>*BB-12\u00ae e LA-5\u00ae, LGG\u00aee TH-4\u00ae sono marchi registrati di Chr. Hansen.<\/p>\n<p><strong>Probiotici che fornisce<\/strong><\/p>\n<ul>\n<li>Bifidobacterium lactis BL818<\/li>\n<li>Lactobacillus acidophilus LA-14<\/li>\n<li>Lactiplantibacillus plantarum Lp-115<\/li>\n<li>Lacticaseibacillus paracasei Lpc-37<\/li>\n<li>Lactobacillus gasseri Lg-36<\/li>\n<li>Lacticaseibacillus casei Lc-11<\/li>\n<li>Bifidobacterium breve Bb-18<\/li>\n<li>Levilactobacillus brevis Lbr-35<\/li>\n<li>Lacticaseibacillus rhamnosus LR-32<\/li>\n<li>Ligilactobacillus salivarius Ls-33<\/li>\n<li>Bifidobacterium longum subsp. infantis Bi-26<\/li>\n<li>Lactobacillus delbrueckii subsp. bulgaricus Lb-87<\/li>\n<li>Bifidobacterium bifidum Bb-06<\/li>\n<\/ul>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Amido di patata; Capsula vegetale: Idrossi-propil-metilcellulosa; Amido di mais; B. lactis BL818, L. acidophilus LA-14, L. plantarum Lp\u001e115, L. gasseri Lg-36, L. paracasei Lpc-37, B. bifidum Bb-06, B. longum subsp. infantis Bi-26, B. breve Bb-18, L. brevis Lbr-35, L. delbrueckii subsp. bulgaricus Lb-87, L. casei Lc-11, L. salivarius Ls 33, L. rhamnosus LR-32.<\/p>\n<p><strong>Senza glutine<\/strong><br \/>\n<strong>Senza lattosio<\/strong><br \/>\n<strong>Vegetariano<\/strong><br \/>\n<strong>Vegano<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bioflor new formula 30 capsule vegetali &#8211; Solgar. Nuova Formula con 13 Ceppi BIOFLOR \u00e8 un integratore alimentare formulato per un uso quotidiano a base di 13 ceppi di probiotici accuratamente selezionati per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale, garantendo&#8230;<\/p>\n","protected":false},"featured_media":133584,"template":"","meta":{"_acf_changed":false},"product_brand":[9591],"product_cat":[9787],"product_tag":[10575,10574,10577,10528,10576],"giftcard-category":[],"class_list":{"0":"post-133581","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-solgar","7":"product_cat-benessere-gastro-intestinale","8":"product_tag-bioflor","9":"product_tag-capsule","10":"product_tag-new","11":"product_tag-solgar","12":"product_tag-vegetali","13":"pa_formato-30-capsule","14":"pa_marca-solgar","15":"pa_tipologia-capsule","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T17:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"408\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/\",\"name\":\"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg\",\"datePublished\":\"2026-03-20T11:28:29+00:00\",\"dateModified\":\"2026-03-25T17:24:12+00:00\",\"description\":\"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg\",\"width\":408,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra","description":"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/","og_locale":"it_IT","og_type":"article","og_title":"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra","og_description":"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-03-25T17:24:12+00:00","og_image":[{"width":408,"height":466,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/","name":"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg","datePublished":"2026-03-20T11:28:29+00:00","dateModified":"2026-03-25T17:24:12+00:00","description":"Formulato per un uso quotidiano a base di 13 ceppi di probiotici per la loro capacit\u00e0 di sopravvivere alle difficili condizioni del tratto gastrointestinale","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2026\/03\/00001075-bioflor-solgar-nuova-formula-con-13-ceppi-senza-lattosio-latto-derivati-glutine-erboristerie-com.jpg","width":408,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/bioflor-new-formula-con-13-ceppi-senza-lattosio-e-glutine-30-capsule-vegetali-solgar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Bioflor New Formula con 13 Ceppi Senza lattosio e glutine 30 capsule vegetali Solgar"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/133581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/133584"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=133581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=133581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=133581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=133581"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=133581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}