{"id":116818,"date":"2022-09-24T11:18:57","date_gmt":"2022-09-24T09:18:57","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=116818"},"modified":"2025-04-04T09:48:30","modified_gmt":"2025-04-04T07:48:30","slug":"sapone-di-aleppo-liquido-al-20-di-alloro-500ml","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/","title":{"rendered":"Sapone di Aleppo liquido al 20% di Alloro 500ml"},"content":{"rendered":"<p><strong>Sapone di Aleppo liquido al 20% di Alloro 500ml<\/strong><\/p>\n<p>Il sapone di Aleppo \u00e8 biodegradabile al 100%, <strong>adatto ad ogni tipo di pelle, anallergico e delicato<\/strong>.<\/p>\n<p>\u00c8 un ottimo antinfiammatorio e antisettico naturale ed \u00e8 particolarmente indicato per chi \u00e8 affetto da acne, psoriasi, forfora, dermatiti, allergie o intolleranze ai profumi.<\/p>\n<p>Ideale per la rasatura e la depilazione, \u00e8 ottimo come maschera cosmetica purificante per il viso, soprattutto in caso di pelle grassa e con acne, e pu\u00f2 essere utilizzato anche per il bucato.<\/p>\n<p>Essendo molto delicato \u00e8 <strong>ottimo anche per bambini e anziani<\/strong>.<\/p>\n<p><strong>\u200bIngredienti<\/strong><\/p>\n<p>Aqua, Olea Europea fruit oil, Laurus Nobilis fruit oil, Potassium Hydroxide.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sapone di Aleppo liquido al 20% di Alloro 500ml Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. \u00c8 un ottimo antinfiammatorio e antisettico naturale ed \u00e8 particolarmente indicato per chi \u00e8 affetto da acne, psoriasi, forfora,&#8230;<\/p>\n","protected":false},"featured_media":116852,"template":"","meta":{"_acf_changed":false},"product_brand":[9602],"product_cat":[45044],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-116818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-himalaya","7":"product_cat-detergenza","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-04T07:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"346\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/\",\"name\":\"Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg\",\"datePublished\":\"2022-09-24T09:18:57+00:00\",\"dateModified\":\"2025-04-04T07:48:30+00:00\",\"description\":\"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg\",\"width\":346,\"height\":491},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sapone di Aleppo liquido al 20% di Alloro 500ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra","description":"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/","og_locale":"it_IT","og_type":"article","og_title":"Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra","og_description":"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-04-04T07:48:30+00:00","og_image":[{"width":346,"height":491,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/","name":"Sapone di Aleppo liquido al 20% di Alloro 500ml - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg","datePublished":"2022-09-24T09:18:57+00:00","dateModified":"2025-04-04T07:48:30+00:00","description":"Il sapone di Aleppo \u00e8 biodegradabile al 100%, adatto ad ogni tipo di pelle, anallergico e delicato. Ottimo anche per bambini e anziani.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/09\/00007209-1.jpg","width":346,"height":491},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/sapone-di-aleppo-liquido-al-20-di-alloro-500ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Sapone di Aleppo liquido al 20% di Alloro 500ml"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/116818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/116852"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=116818"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=116818"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=116818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=116818"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=116818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}