{"id":112707,"date":"2021-10-10T18:53:43","date_gmt":"2021-10-10T16:53:43","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=112707"},"modified":"2025-09-13T14:33:24","modified_gmt":"2025-09-13T12:33:24","slug":"olio-essenziale-di-incenso-biologico-5ml-nasoterapia","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/","title":{"rendered":"Olio essenziale di Incenso Biologico 5ml &#8211; Nasoterapia"},"content":{"rendered":"<p><strong>Olio essenziale di Incenso Biologico (Boswellia serrata) 5ml<em> &#8211; Nasoterapia<\/em><\/strong><\/p>\n<p><strong>Rilassante<\/strong> del sistema nervoso centrale<\/p>\n<p>L&#8217;olio essenziale di Incenso Biologico (Boswellia serrata)\u00a0\u00e8 <strong>100% puro ed \u00e8 utilizzabile come alimento,<\/strong> anche in cucina, come profumatore per ambienti e tessuti <strong>o per utilizzi sul corpo opportunamente diluito in creme o oli vegetali<\/strong> (ad esempio, olio di Mandorle, olio di Jojoba, olio di germe e altri)<\/p>\n<p><strong>Curiosita&#8217;<\/strong><\/p>\n<p>La resa estrattiva si aggira intorno allo 0,1 &#8211; 3%, salvo rare eccezioni<\/p>\n<p><strong>Modo d&#8217;uso<\/strong><br \/>\n&#8211;<strong>Per Alimenti: <\/strong>1 goccia e&#8217; sufficiente per aromatizzare 100gr o 100ml di alimento o bevanda.<br \/>\n<strong>-Per Ambienti:<\/strong> 8-10 gocce nel diffusore per aromatizzare una stanza<\/p>\n<p><strong>Oli essenziali di Nasoterapia 100% puri<\/strong><br \/>\nSeguendo rigorosi protocolli qualitativi, la produzione degli oli avviene tramite distillazione in corrente di vapore o con spremitura a freddo, senza l\u2019impiego di additivi o coloranti che danneggerebbero i delicati equilibri olfattivi e funzionali delle essenze.<\/p>\n<p>Il risultato \u00e8 un mondo allo stato puro creato per profumare ogni angolo della casa e dell\u2019ambiente di lavoro, infondendo buonumore e purificando l\u2019aria, ma anche per arricchire e insaporire gli alimenti, per favorire l\u2019igiene e la bellezza del corpo, del viso, dei capelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olio essenziale di Incenso Biologico (Boswellia serrata) 5ml &#8211; Nasoterapia Rilassante del sistema nervoso centrale L&#8217;olio essenziale di Incenso Biologico (Boswellia serrata)\u00a0\u00e8 100% puro ed \u00e8 utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito&#8230;<\/p>\n","protected":false},"featured_media":112709,"template":"","meta":{"_acf_changed":false},"product_brand":[9649],"product_cat":[45109,9719,9675],"product_tag":[10857,17810,10802,11933,13310,10591,13698,10671],"giftcard-category":[],"class_list":{"0":"post-112707","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-nasoterapia-di-hp-italia","7":"product_cat-oli-essenziali-4","8":"product_cat-diffusori-profumi-ambiente","9":"product_cat-incensi-e-incenserie","10":"product_tag-10857","11":"product_tag-10ml","12":"product_tag-con","13":"product_tag-essenziale","14":"product_tag-essenziali","15":"product_tag-nasoterapia","16":"product_tag-oli","17":"product_tag-olio","18":"pa_formato-5-ml","19":"pa_marca-nasoterapia","20":"pa_tipologia-olio-essenziale","22":"first","23":"instock","24":"sale","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T12:33:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"988\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/\",\"name\":\"Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg\",\"datePublished\":\"2021-10-10T16:53:43+00:00\",\"dateModified\":\"2025-09-13T12:33:24+00:00\",\"description\":\"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg\",\"width\":660,\"height\":988},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti i prodotti\",\"item\":\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Olio essenziale di Incenso Biologico 5ml &#8211; Nasoterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"La tua salute al naturale\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra","description":"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/","og_locale":"it_IT","og_type":"article","og_title":"Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra","og_description":"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-13T12:33:24+00:00","og_image":[{"width":660,"height":988,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/","name":"Olio essenziale di Incenso Biologico 5ml - Nasoterapia - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg","datePublished":"2021-10-10T16:53:43+00:00","dateModified":"2025-09-13T12:33:24+00:00","description":"Puro 100% e utilizzabile come alimento, anche in cucina, come profumatore per ambienti e tessuti o per utilizzi sul corpo opportunamente diluito","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2021\/10\/00010948.jpg","width":660,"height":988},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/olio-essenziale-di-incenso-biologico-5ml-nasoterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutti i prodotti","item":"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/"},{"@type":"ListItem","position":3,"name":"Olio essenziale di Incenso Biologico 5ml &#8211; Nasoterapia"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"La tua salute al naturale","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product\/112707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media\/112709"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/media?parent=112707"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_brand?post=112707"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_cat?post=112707"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/product_tag?post=112707"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/it\/wp-json\/wp\/v2\/giftcard-category?post=112707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}