{"id":10152,"count":0,"description":"Il rispetto dell'energia di vita delle piante: \u00e8 stata questa, fin dagli inizi, una delle regole-guida dell'azienda Dr. Giorgini<br \/>\nL\u2019<strong>Azienda Dr. Giorgini<\/strong>\u00a0nasce nel lontano\u00a0<strong>1977<\/strong>\u00a0da una\u00a0<strong>semplice erboristeria<\/strong>. A quel tempo nelle erboristerie si vendevano esclusivamente erbe officinali, con cui si potevano preparare tisane a casa propria mediante infusione in acqua calda.<br \/>\nIl\u00a0Dott. Giorgini\u00a0matura allora l\u2019idea di preparare delle\u00a0<strong>soluzioni<\/strong>\u00a0che si possano assumere velocemente\u00a0<strong>con mezzo bicchiere d'acqua<\/strong>: nascono cos\u00ec le\u00a0tisane concentrate e pronte all\u2019uso.<br \/>\nDai preparati liquidi alle pastiglie il passo \u00e8 breve. Questa nuova\u201cmoda\u201d piace e diffonde il consumo delle piante medicinali in maniera esponenziale, anche per mezzo di\u00a0<strong>ditte imitatrici.<\/strong><\/p>\n\nUn metodo innovativo: l'elemento peculiare e inimitabile del prodotti Dr. Giorgini\n\nLa peculiarit\u00e0 dei prodotti preparati dal Dr. Giorgini \u00e8 per\u00f2 un'altra: risiede infatti un'<strong>innovativa tecnica di lavorazione<\/strong>\u00a0(Metodo Alchemico<sup>\u00ae<\/sup>\u00a0Spagyrico<sup>\u00ae<\/sup>), che tiene conto sia dei\u00a0<strong>principi attivi<\/strong>\u00a0delle piante (con attivit\u00e0 fisiologica e\/o nutritiva) sia della loro\u00a0<strong>energia di vita<\/strong>, al fine di ottenere\u00a0<strong>estrazioni vegetali veramente totali.<\/strong><br \/>\nLa filosofia aziendale ruota proprio attorno al concetto di\u00a0<em><strong>energia di vita<\/strong><\/em>. Questa preziosa energia si pu\u00f2 identificare\u00a0<strong>nella luce solare fissata<\/strong>\u00a0nei vegetali mediante la fotosintesi clorofilliana.<br \/>\nPer prima cosa, fondamentale \u00e8 la\u00a0<strong>scelta di materie prime<\/strong>\u00a0che, oltre a garantire le qualit\u00e0 ordinariamente richieste,\u00a0<strong>non devono essere state irradiate.<\/strong><br \/>\nProseguendo nella filiera produttiva,\u00a0<strong>si evitano inoltre quelle tecniche che potrebbero ridurre o distruggere l\u2019energia di vita<\/strong>\u00a0ancora presente nelle piante (come pressione e calore superiori a quelli dell\u2019ambiente, ultrasuoni, microonde, acidi e basi forti ecc.).<\/h2>","link":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/","name":"Dr. Giorgini","slug":"dr-giorgini-en","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dr. Giorgini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Giorgini\" \/>\n<meta property=\"og:description\" content=\"Il rispetto dell&#8217;energia di vita delle piante: \u00e8 stata questa, fin dagli inizi, una delle regole-guida dell&#8217;azienda Dr. Giorgini L\u2019Azienda Dr. Giorgini\u00a0nasce nel lontano\u00a01977\u00a0da una\u00a0semplice erboristeria. A quel tempo nelle erboristerie si vendevano esclusivamente erbe officinali, con cui si potevano preparare tisane a casa propria mediante infusione in acqua calda. Il\u00a0Dott. Giorgini\u00a0matura allora l\u2019idea di preparare delle\u00a0soluzioni\u00a0che si possano assumere velocemente\u00a0con mezzo bicchiere d&#8217;acqua: nascono cos\u00ec le\u00a0tisane concentrate e pronte all\u2019uso. Dai preparati liquidi alle pastiglie il passo \u00e8 breve. Questa nuova\u201cmoda\u201d piace e diffonde il consumo delle piante medicinali in maniera esponenziale, anche per mezzo di\u00a0ditte imitatrici. Un metodo innovativo: l&#8217;elemento peculiare e inimitabile del prodotti Dr. Giorgini La peculiarit\u00e0 dei prodotti preparati dal Dr. Giorgini \u00e8 per\u00f2 un&#8217;altra: risiede infatti un&#8217;innovativa tecnica di lavorazione\u00a0(Metodo Alchemico\u00ae\u00a0Spagyrico\u00ae), che tiene conto sia dei\u00a0principi attivi\u00a0delle piante (con attivit\u00e0 fisiologica e\/o nutritiva) sia della loro\u00a0energia di vita, al fine di ottenere\u00a0estrazioni vegetali veramente totali. La filosofia aziendale ruota proprio attorno al concetto di\u00a0energia di vita. Questa preziosa energia si pu\u00f2 identificare\u00a0nella luce solare fissata\u00a0nei vegetali mediante la fotosintesi clorofilliana. Per prima cosa, fondamentale \u00e8 la\u00a0scelta di materie prime\u00a0che, oltre a garantire le qualit\u00e0 ordinariamente richieste,\u00a0non devono essere state irradiate. Proseguendo nella filiera produttiva,\u00a0si evitano inoltre quelle tecniche che potrebbero ridurre o distruggere l\u2019energia di vita\u00a0ancora presente nelle piante (come pressione e calore superiori a quelli dell\u2019ambiente, ultrasuoni, microonde, acidi e basi forti ecc.).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/\",\"url\":\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/\",\"name\":\"Dr. Giorgini\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Giorgini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Giorgini","og_description":"Il rispetto dell&#8217;energia di vita delle piante: \u00e8 stata questa, fin dagli inizi, una delle regole-guida dell&#8217;azienda Dr. Giorgini L\u2019Azienda Dr. Giorgini\u00a0nasce nel lontano\u00a01977\u00a0da una\u00a0semplice erboristeria. A quel tempo nelle erboristerie si vendevano esclusivamente erbe officinali, con cui si potevano preparare tisane a casa propria mediante infusione in acqua calda. Il\u00a0Dott. Giorgini\u00a0matura allora l\u2019idea di preparare delle\u00a0soluzioni\u00a0che si possano assumere velocemente\u00a0con mezzo bicchiere d&#8217;acqua: nascono cos\u00ec le\u00a0tisane concentrate e pronte all\u2019uso. Dai preparati liquidi alle pastiglie il passo \u00e8 breve. Questa nuova\u201cmoda\u201d piace e diffonde il consumo delle piante medicinali in maniera esponenziale, anche per mezzo di\u00a0ditte imitatrici. Un metodo innovativo: l&#8217;elemento peculiare e inimitabile del prodotti Dr. Giorgini La peculiarit\u00e0 dei prodotti preparati dal Dr. Giorgini \u00e8 per\u00f2 un&#8217;altra: risiede infatti un&#8217;innovativa tecnica di lavorazione\u00a0(Metodo Alchemico\u00ae\u00a0Spagyrico\u00ae), che tiene conto sia dei\u00a0principi attivi\u00a0delle piante (con attivit\u00e0 fisiologica e\/o nutritiva) sia della loro\u00a0energia di vita, al fine di ottenere\u00a0estrazioni vegetali veramente totali. La filosofia aziendale ruota proprio attorno al concetto di\u00a0energia di vita. Questa preziosa energia si pu\u00f2 identificare\u00a0nella luce solare fissata\u00a0nei vegetali mediante la fotosintesi clorofilliana. Per prima cosa, fondamentale \u00e8 la\u00a0scelta di materie prime\u00a0che, oltre a garantire le qualit\u00e0 ordinariamente richieste,\u00a0non devono essere state irradiate. Proseguendo nella filiera produttiva,\u00a0si evitano inoltre quelle tecniche che potrebbero ridurre o distruggere l\u2019energia di vita\u00a0ancora presente nelle piante (come pressione e calore superiori a quelli dell\u2019ambiente, ultrasuoni, microonde, acidi e basi forti ecc.).","og_url":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/","og_site_name":"Erboristeria Demetra","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/","url":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/","name":"Dr. Giorgini","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/en\/product-category\/dr-giorgini-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"Dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat\/10152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product?product_cat=10152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}