{"id":78830,"date":"2019-09-12T19:26:13","date_gmt":"2019-09-12T17:26:13","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=78830"},"modified":"2026-01-30T12:47:58","modified_gmt":"2026-01-30T11:47:58","slug":"magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/","title":{"rendered":"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico"},"content":{"rendered":"<p><strong>Magnesio Cloruro Over 50 Liquido analcoolico &#8211; dr. Giorgini<\/strong><\/p>\n<p>Flacone da 500 ml<\/p>\n<p>Stanchezza e affaticamento<\/p>\n<p>Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, coadiuva il funzionamento del sistema nervoso e mantiene le normali funzioni psicologiche.<\/p>\n<p>Interviene nei processi di divisione cellulare, favorisce l\u2019equilibrio elettrolitico, la sintesi proteica, la normale funzione muscolare e il benessere di ossa e denti.<\/p>\n<p>La betaina contribuisce al normale metabolismo dell\u2019omocisteina*.<\/p>\n<p>L\u2019acido folico favorisce la sintesi degli aminoacidi e di tutte le cellule del sangue (emopoiesi), e interviene nel processo di divisione cellulare.<\/p>\n<p>La vitamina C contribuisce al mantenimento della normale funzione del sistema immunitario durante e dopo uno sforzo fisico intenso**, nonch\u00e9 alla formazione del collagene per la normale funzione di vasi sanguigni, ossa, cartilagini, gengive, pelle e denti; favorisce la protezione delle cellule dallo stress ossidativo, la rigenerazione della forma ridotta della vitamina E e accresce l\u2019assorbimento del ferro.<\/p>\n<p>La vitamina B12 sostiene la normale formazione dei globuli rossi, mentre la vitamina B6 contribuisce alla normale sintesi della cisteina, al normale metabolismo delle proteine e del glicogeno e alla regolazione dell\u2019attivit\u00e0 ormonale.<\/p>\n<p>L\u2019effetto benefico \u00e8 ottenibile con l\u2019assunzione giornaliera di:<br \/>\n*1500 mg di betaina.<br \/>\n**200 mg di vitamina C in aggiunta all\u2019apporto giornaliero raccomandato.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 10 ml diluiti in un bicchiere d\u2019acqua, da una a tre volte al giorno in qualunque momento (da 10 a 30 ml al giorno); dolcificare a piacere.<\/p>\n<p>Se desiderato, la dose giornaliera pu\u00f2 essere diluita in una bottiglia d\u2019acqua da consumare nell\u2019arco della giornata.<\/p>\n<p>Agitare prima dell\u2019uso.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicerina vegetale bidistillata, acqua pura, betaina base, magnesio cloruro esaidrato, rosa canina (Rosa canina) frutti estratto integrale secco contenente l\u2019intero fitocomplesso (titolato al 50% in vitamina C), vitamina B6 (piridossina cloridrato), vitamina B12 (cianocobalamina), acido folico.<\/p>\n<p><strong>Informazioni aggiuntive<\/strong><\/p>\n<p>10 ml contengono mediamente: 1,26 g di magnesio cloruro esaidrato che corrisponde a 150 mg (40% NRV) di magnesio.<\/p>\n<p><strong>Non contiene alcool, conservanti, coloranti, aromi ed edulcoranti di sintesi.<\/strong><\/p>\n<p>Conservare il prodotto fuori dal frigorifero anche dopo l\u2019apertura.<\/p>\n<p><strong>Prodotto adatto ai vegani.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magnesio Cloruro Over 50 Liquido analcoolico &#8211; dr. Giorgini Flacone da 500 ml Stanchezza e affaticamento Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, coadiuva il funzionamento del sistema nervoso e mantiene le normali funzioni psicologiche. Interviene nei processi di&#8230;<\/p>\n","protected":false},"featured_media":109243,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46274,46275,10163,9799],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-78830","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-energia-e-vitalita","8":"product_cat-dr-vitamine","9":"product_cat-linea-oro-classica","10":"product_cat-vitamine-e-minerali","11":"pa_formato-500-ml","12":"pa_linea-linea-oro","13":"pa_marca-dr-giorgini","14":"pa_tipologia-liquido-analcolico","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/\",\"name\":\"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg\",\"datePublished\":\"2019-09-12T17:26:13+00:00\",\"dateModified\":\"2026-01-30T11:47:58+00:00\",\"description\":\"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg\",\"width\":586,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra","description":"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/","og_locale":"en_US","og_type":"article","og_title":"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra","og_description":"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:47:58+00:00","og_image":[{"width":586,"height":586,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/","name":"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg","datePublished":"2019-09-12T17:26:13+00:00","dateModified":"2026-01-30T11:47:58+00:00","description":"Il magnesio contribuisce a ridurre la stanchezza e l\u2019affaticamento promuovendo il metabolismo energetico, il sistema nervoso e le funzioni psicologiche","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/09\/00007179-2.jpg","width":586,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/magnesio-cloruro-over-50-dr-giorgini-500ml-analcolico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Magnesio Cloruro Over 50 Dr. Giorgini 500ml analcolico"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/78830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/109243"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=78830"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=78830"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=78830"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=78830"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=78830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}