{"id":71478,"date":"2016-03-01T18:11:10","date_gmt":"2016-03-01T17:11:10","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=71478"},"modified":"2025-08-30T10:02:52","modified_gmt":"2025-08-30T08:02:52","slug":"borsa-del-pastore-estratto-integrale-200-ml","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/","title":{"rendered":"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini"},"content":{"rendered":"<p><strong>Borsa pastore Estratto Integrale\u00a0Liquido analcoolico 200 ml &#8211; dr. Giorgini<\/strong><\/p>\n<p>La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit\u00e0 delle vie urinarie.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 10 ml diluiti in un bicchiere d\u2019acqua, una o due volte al giorno in qualunque momento (da 10 a 20 ml al giorno); mescolare e dolcificare a piacere.<\/p>\n<p>Se desiderato, la dose giornaliera pu\u00f2 essere diluita in una bottiglia d\u2019acqua da consumare nell\u2019arco della giornata.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicerina vegetale bidistillata, acqua pura, borsa pastore (Capsella bursa-pastoris) erba.<\/p>\n<p><strong>Non contiene alcool, conservanti, coloranti, aromi ed edulcoranti di sintesi.<\/strong><\/p>\n<p><strong>Conservare il prodotto fuori dal frigorifero anche dopo l\u2019apertura.<\/strong><\/p>\n<p><strong>Prodotto adatto ai vegani.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Borsa pastore Estratto Integrale\u00a0Liquido analcoolico 200 ml &#8211; dr. Giorgini La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit\u00e0 delle vie urinarie. Consigli d&#8217;uso Si consiglia l\u2019assunzione di 10 ml diluiti in un bicchiere d\u2019acqua,&#8230;<\/p>\n","protected":false},"featured_media":119973,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46270,10371],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-71478","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-benessere-della-donna","8":"product_cat-estratti-integrali","9":"pa_formato-200-ml","10":"pa_linea-estratti-integrali","11":"pa_marca-dr-giorgini","12":"pa_tipologia-liquido-analcolico","14":"first","15":"instock","16":"sale","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.&#039;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-30T08:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/\",\"name\":\"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg\",\"datePublished\":\"2016-03-01T17:11:10+00:00\",\"dateModified\":\"2025-08-30T08:02:52+00:00\",\"description\":\"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.'\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","description":"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/","og_locale":"en_US","og_type":"article","og_title":"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","og_description":"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.'","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-08-30T08:02:52+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/","name":"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg","datePublished":"2016-03-01T17:11:10+00:00","dateModified":"2025-08-30T08:02:52+00:00","description":"La borsa pastore contrasta i disturbi del ciclo mestruale e promuove il drenaggio dei liquidi corporei e la funzionalit? delle vie urinarie.'","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2016\/03\/00004056-borsadelpastore-integrale200.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/borsa-del-pastore-estratto-integrale-200-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Borsa pastore Estratto Integrale analcoolico 200ml dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/71478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/119973"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=71478"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=71478"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=71478"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=71478"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=71478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}