{"id":65178,"date":"2013-05-11T00:00:00","date_gmt":"2013-05-11T00:00:00","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=65178"},"modified":"2025-09-03T22:16:21","modified_gmt":"2025-09-03T20:16:21","slug":"maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/","title":{"rendered":"Maschera all&#8217;argilla Tonificante 100ml ad azione tonificante e revulsiva"},"content":{"rendered":"<p><b>Maschera all&#8217;argilla Tonificante 100 ml &#8211; dr. Giorgini<\/b><\/p>\n<p>Maschera viso ad azione tonificante e revulsiva, a base di tessuti embrionali o meristematici freschi di mirtillo nero, ippocastano e castagno che stimolano la microcircolazione e il benessere dei capillari.<\/p>\n<p>Estratti vegetali drenanti e coadiuvanti di betulla, ananas, pungitopo e centella; olio di lino emolliente; principi attivi nutritivi, minerali e vitamine ad azione ricostituente.<\/p>\n<p>Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per sgonfiare e rassodare l\u2019aspetto del volto rendendolo fresco e disteso.<\/p>\n<p><strong>Ingredients INCI<\/strong><\/p>\n<p>Glycerin, Solum follonum (25%), Kaolin (12,5%), Aqua, Linum usitatissimum seed oil, Sorbitan oleate, Calamine, Tocopherol, Aesculus hippocastanum bud extract, Castanea sativa bud extract, Betula alba leaf extract, Centella asiatica leaf extract, Vaccinium myrtillus bud extract, Ruscus aculeatus root extract, Potassium chloride, Ananas sativus stem extract, Melilolus officinalis herb extract, Ascorbic acid, Niacin, Panthenol, Xanthan gum, Zinc gluconate, Inositol, Manganese gluconate, Citric acid, Dimethyl sulfone, Glutathione, Histidine, Retinyl palmitate, Ascorbyl tetraisopalmitate, Sodium hyaluronate, Pyridoxine HCl, Riboflavin, Thiamine HCl, Biotin, Cyanocobalamin, Folic acid, Potassium iodide.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Applicare sulla pelle del viso una quantit\u00e0 di prodotto sufficiente a coprire la cute; lasciare in applicazione per circa 15-30 minuti. Rimuovere il prodotto lavando con abbondante acqua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maschera all&#8217;argilla Tonificante 100 ml &#8211; dr. Giorgini Maschera viso ad azione tonificante e revulsiva, a base di tessuti embrionali o meristematici freschi di mirtillo nero, ippocastano e castagno che stimolano la microcircolazione e il benessere dei capillari. Estratti vegetali drenanti e coadiuvanti di betulla,&#8230;<\/p>\n","protected":false},"featured_media":65179,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[10203,45097],"product_tag":[16325,11439,11060,10949],"giftcard-category":[],"class_list":{"0":"post-65178","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-cosmetici-viso","8":"product_cat-argille-e-fanghi","9":"product_tag-allargilla","10":"product_tag-carota","11":"product_tag-maschera","12":"product_tag-tonificante","13":"pa_formato-100-ml","14":"pa_linea-cosmetici","15":"pa_marca-dr-giorgini","16":"pa_tipologia-maschera","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maschera all&#039;argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maschera all&#039;argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T20:16:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/\",\"name\":\"Maschera all'argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg\",\"datePublished\":\"2013-05-11T00:00:00+00:00\",\"dateModified\":\"2025-09-03T20:16:21+00:00\",\"description\":\"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg\",\"width\":\"640\",\"height\":\"538\",\"caption\":\"MASCHERA ALL'ARGILLA TONIFICANTE 100 ML\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maschera all&#8217;argilla Tonificante 100ml ad azione tonificante e revulsiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maschera all'argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra","description":"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/","og_locale":"en_US","og_type":"article","og_title":"Maschera all'argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra","og_description":"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-03T20:16:21+00:00","og_image":[{"width":640,"height":538,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/","name":"Maschera all'argilla Tonificante 100ml ad azione tonificante e revulsiva - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg","datePublished":"2013-05-11T00:00:00+00:00","dateModified":"2025-09-03T20:16:21+00:00","description":"Indicata per tutti i tipi di pelle, risulta utile per donare vitalit\u00e0 alla cute stanca, per rassodare l\u2019aspetto del volto rendendolo fresco e disteso.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00010163.jpg","width":"640","height":"538","caption":"MASCHERA ALL'ARGILLA TONIFICANTE 100 ML"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/maschera-allargilla-tonificante-100ml-ad-azione-tonificante-e-revulsiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Maschera all&#8217;argilla Tonificante 100ml ad azione tonificante e revulsiva"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/65178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/65179"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=65178"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=65178"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=65178"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=65178"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=65178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}