{"id":62778,"date":"2013-05-11T00:00:00","date_gmt":"2013-05-11T00:00:00","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=62778"},"modified":"2026-01-30T12:25:29","modified_gmt":"2026-01-30T11:25:29","slug":"daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/","title":{"rendered":"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale"},"content":{"rendered":"<p><strong>Daunadieci\u00a0100 pastiglie &#8211; dr. Giorgini<\/strong><\/p>\n<p>La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.<\/p>\n<p>Inoltre, il finocchio promuove la regolare motilit\u00e0 gastrointestinale e l\u2019eliminazione dei gas.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione da 1 a 10 pastiglie una volta al giorno in qualunque momento; suggerito la sera prima di cena o prima di coricarsi. Richiudere accuratamente dopo l&#8217;utilizzo.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Cascara (Rhamnus purshiana) cortecce polvere, taurina, glicina, cellulosa microcristallina\u00b0, gomma arabica\u00b0, cremor tartaro di vino purificato, (L-)istidina, (L-)lisina cloridrato, (L-)metionina, NAC (N-acetilcisteina), rosa canina (Rosa canina) frutti E.S (titolato al 70% in vitamina C), silicio biossido\u00b0\u00b0, finocchio (Foeniculum vulgare) frutti O.E., vitamina E di origine naturale (acetato di D-\u03b1-tocoferile), fermenti lattici (Bacillus coagulans o Lactobacillus sporanges ATCC 7050), acerola (Malpighia glabra) frutti E.S. (titolato al 50% in vitamina C), magnesio stearato di origine vegetale\u00b0\u00b0, vitamina B3 (nicotinamide), vitamina B5 (pantotenato di calcio), vitamina A (acetato di retinile), vitamina B6 (piridossina cloridrato), vitamina K1 (fillochinone), vitamina B2 (riboflavina), vitamina B1 (tiamina cloridrato), acido folico, biotina, vitamina D3 (colecalciferolo) di origine vegetale (estratta da lichene Cladonia rangiferina), vitamina B12 (cianocobalamina).<br \/>\n\u00b0Agente di carica. \u00b0\u00b0Antiagglomerante.<br \/>\nE.S.= Estratto secco. O.E.= Olio essenziale (Aetheroleum). NRV= Valore nutritivo di riferimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daunadieci\u00a0100 pastiglie &#8211; dr. Giorgini La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva. Inoltre, il finocchio promuove la regolare motilit\u00e0 gastrointestinale e l\u2019eliminazione dei gas. Consigli d&#8217;uso Si consiglia l\u2019assunzione da 1 a 10 pastiglie una volta&#8230;<\/p>\n","protected":false},"featured_media":119197,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[10163],"product_tag":[15253,18177,18178,14699],"giftcard-category":[],"class_list":{"0":"post-62778","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-linea-oro-classica","8":"product_tag-daunadieci","9":"product_tag-dr-2","10":"product_tag-giorgini-2","11":"product_tag-pastiglie","12":"pa_formato-100-pastiglie","13":"pa_linea-linea-oro","14":"pa_marca-dr-giorgini","15":"pa_tipologia-compresse","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:25:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/\",\"name\":\"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg\",\"datePublished\":\"2013-05-11T00:00:00+00:00\",\"dateModified\":\"2026-01-30T11:25:29+00:00\",\"description\":\"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra","description":"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/","og_locale":"en_US","og_type":"article","og_title":"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra","og_description":"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:25:29+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/","name":"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg","datePublished":"2013-05-11T00:00:00+00:00","dateModified":"2026-01-30T11:25:29+00:00","description":"La cascara favorisce la regolarit\u00e0 del transito intestinale e, insieme al finocchio, sostiene la funzione digestiva.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009689-daunadieci-pastiglie.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/daunadieci-100-pastiglie-dr-giorgini-per-la-regolare-motilita-gastrointestinale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Daunadieci\u00a0100 pastiglie dr. Giorgini per la regolare motilit\u00e0 gastrointestinale"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/62778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/119197"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=62778"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=62778"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=62778"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=62778"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=62778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}