{"id":58798,"date":"2010-05-26T12:31:03","date_gmt":"2010-05-26T10:31:03","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=58798"},"modified":"2025-09-10T18:54:41","modified_gmt":"2025-09-10T16:54:41","slug":"fiore-dell-onda-profumo-50ml","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/fiore-dell-onda-profumo-50ml\/","title":{"rendered":"Fiore dell&#8217;Onda Profumo  50ml"},"content":{"rendered":"<p><strong>FIORE DELL&#8217;ONDA PROFUMO 50 ML &#8211; L&#8217;Erbolario<\/strong><br \/>\nVigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera&#8217; un&#8217;infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu<br \/>\n<strong>Descrizione<\/strong><br \/>\nSono infinite le suggestioni che le fresche note di questa profumazione sanno evocare: il suono ritmato delle spumose onde del mare, la grazia infinita dei fiori adagiati sull\u2019acqua, il sommesso soffiare di un vento salmastro. Una fragranza che sa dialogare con l\u2019animo e svelare il fascino naturale di chi lo sceglie.<\/p>\n<ul>\n<li>Fragranza fiorita, acquatica<\/li>\n<li>Profumo fiorito acquatico <strong>unisex<\/strong><\/li>\n<li>Note di: Alghe rosse, Fior di Ninfea blu, Muschi bianchi<\/li>\n<\/ul>\n<p><strong>FIORE DELL&#8217;ONDA, LA BELLEZZA DAL MARE<\/strong><br \/>\nPer chi delle spalancate distese marine soffra la nostalgia e per chi durante tutto l&#8217;anno avverta il desiderio di rituffare il pensiero tra i flutti salati e ridenti, la linea Fiore dell&#8217;Onda ha catturato la nota aromatica e pungente della brezza marina e l&#8217;ha qui sposata alla fragranza di sale che in mare fiorisce ad ogni infrangersi di onda.<br \/>\nNasce cos\u00ec un profumo penetrante e dalla verve indomita, che cavalca come un&#8217;onda questa linea da bagno completa e freschissima. Nelle sue formulazioni calibrate verdeggiano gli estratti benefici di piante che, solo posate o a fondo calate nell&#8217;acqua, dall&#8217;acqua traggono tutta la loro forza vitale e la loro bellezza. La purpurea Alga Nori e la Ninfea Blu dai mirabili fiori a punta generosamente declinano in un Bagnoschiuma, in una Crema Fluida e in un Sapone il loro invidiabile corredo di flavonoidi, sali minerali, proteine e vitamine.<br \/>\nAssicurano cos\u00ec ogni giorno alla pelle del corpo un velo di morbidezza e protezione, nonch\u00e9 un irrinunciabile contributo nella lotta al precoce invecchiamento cutaneo e alle antiestetiche perdite di tono.<\/p>\n<p><strong>Cosa sapere in pi\u00f9<\/strong><\/p>\n<ul>\n<li>100% Made in Italy<br \/>\nOgni fase della nostra attivit\u00e0, dalla formulazione al controllo qualit\u00e0, dalla preparazione del semilavorato al confezionamento, viene attuata da sempre nel nostro sito produttivo di Lodi: noi non abbiamo delocalizzato alcuna fase produttiva in paesi terzi, men che meno in quelli nei quali i diritti umani e i diritti fondamentali dei lavoratori sono calpestati. I nostri fitocosmetici sono orgogliosi di potersi dire 100% MADE IN ITALY!<\/li>\n<li>7 Metalli testatiMonitoraggio del contenuto di 7 metalli per minimizzare i rischi di allergia: *(Nichel, Piombo, Arsenico, Cadmio, Mercurio, Antimonio e Cromo) e salvaguardare cos\u00ec anche le pelli pi\u00f9 sensibili. Ogni lotto di produzione \u00e8 rigorosamente controllato per garantire un contenuto di ogni singolo metallo inferiore a 0.00005% (limite di rilevabilit\u00e0 strumentale).<\/li>\n<li>Da sempre amici degli animali<br \/>\nAderiamo allo \u201cStandard Internazionale Stop ai Test su Animali\u201d; garantito da LAV (Lega Anti Vivisezione). Fin dalla sua fondazione nel 1978 L&#8217;Erbolario ha seguito la politica di non ricorrere a test su animali e dal 2006, dopo che le normative europee hanno iniziato a limitare e poi hanno man mano proibito il ricorso ai test su animali per fini cosmetici, ha aderito allo Standard. www.lav.it<\/li>\n<li>Dermatologicamente Testato<br \/>\nQuesto prodotto ha dimostrato di essere ottimamente tollerato dopo una rigorosa sperimentazione clinica finalizzata alla ricerca di eventuali potenzialit\u00e0 di irritazione e di allergogenesi. La valutazione delle ricerche \u00e8 stata effettuata presso il Dipartimento di Medicina interna e Terapia medica dell\u2019Universit\u00e0 degli Studi di Pavia.<\/li>\n<li>Imballo in Carta FSC\u00ae<br \/>\nLa confezione esterna cartacea di questo prodotto \u00e8 costituita esclusivamente carta certificata FSC\u00ae, secondo i rigorosi standardambientali e sociali del Forest Stewardship Concil\u00ae a supporto di una corretta e responsabile gestione delle risorse forestali<br \/>\nSenza ingredienti di derivazione animale<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>FIORE DELL&#8217;ONDA PROFUMO 50 ML &#8211; L&#8217;Erbolario Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera&#8217; un&#8217;infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu Descrizione Sono infinite le suggestioni che&#8230;<\/p>\n","protected":false},"featured_media":109494,"template":"","meta":{"_acf_changed":false},"product_brand":[9603],"product_cat":[45042],"product_tag":[11423,13263,11758,12238],"giftcard-category":[],"class_list":{"0":"post-58798","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbolario","7":"product_cat-profumi","8":"product_tag-50ml","9":"product_tag-dellonda","10":"product_tag-fiore","11":"product_tag-profumo","12":"pa_formato-50-ml","13":"pa_linea-profumazione-fiore-dellonda","14":"pa_marca-lerbolario","15":"pa_tipologia-profumo","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiore dell&#039;Onda Profumo 50ml<\/title>\n<meta name=\"description\" content=\"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera&#039; un&#039;infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiore dell&#039;Onda Profumo 50ml\" \/>\n<meta property=\"og:description\" content=\"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera&#039; un&#039;infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T16:54:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/\",\"name\":\"Fiore dell'Onda Profumo 50ml\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg\",\"datePublished\":\"2010-05-26T10:31:03+00:00\",\"dateModified\":\"2025-09-10T16:54:41+00:00\",\"description\":\"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera' un'infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg\",\"width\":772,\"height\":763},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiore dell&#8217;Onda Profumo 50ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiore dell'Onda Profumo 50ml","description":"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera' un'infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/","og_locale":"en_US","og_type":"article","og_title":"Fiore dell'Onda Profumo 50ml","og_description":"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera' un'infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-10T16:54:41+00:00","og_image":[{"width":772,"height":763,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/","name":"Fiore dell'Onda Profumo 50ml","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg","datePublished":"2010-05-26T10:31:03+00:00","dateModified":"2025-09-10T16:54:41+00:00","description":"Vigoroso e fresco, penetrante e indomito, un profumo che sulla vostra pelle ogni giorno sollevera' un'infrangersi di memorie salmastre e azzurre. Una fragranza fresca e acquatica come i fiori di Ninfea blu","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2010\/05\/00008296-1.jpg","width":772,"height":763},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/fiore-dell-onda-profumo-50ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Fiore dell&#8217;Onda Profumo 50ml"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/58798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/109494"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=58798"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=58798"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=58798"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=58798"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=58798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}