{"id":57518,"date":"2008-05-06T16:06:57","date_gmt":"2008-05-06T14:06:57","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=57518"},"modified":"2025-09-15T12:15:12","modified_gmt":"2025-09-15T10:15:12","slug":"miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/","title":{"rendered":"Miscela di erbe officinali n.5E &#8211; depurazione del fegato, digestiva 100g"},"content":{"rendered":"<p>Tisana di erbe officinali n.5E &#8211; depurazione del fegato, digestiva 100g<\/p>\n<p>Miscela d&#8217;erbe officinali particolarmente studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica.<\/p>\n<p>E&#8217; una classica formulazione epatica, di sapore piuttosto amarotico adatta anche a chiunque desideri effettuare un periodo di disintossicazione.<\/p>\n<p><strong>Si suggerisce la preparazione in questo modo:<\/strong><br \/>\n1 cucchiaio della miscela per circa 200 ml di acqua (corrispondente ad 1 tazza).<\/p>\n<p>Al bollore, spegnere il gas, inserire le erbe e lasciare riposare, con il coperchio, almeno 10-15 minuti.<\/p>\n<p>Filtrare e bere 2-3 volte al di&#8217; preferibilmente a stomaco vuoto o prima dei pasti (in cui si ha appunto lo stomaco vuoto e si assimilano bene e velocemente i liquidi).<\/p>\n<p>Un&#8217;attenzione puo&#8217; essere quella di assumere 1 sola tazza al di&#8217; all&#8217;inizio della cura per un paio di giorni per poi passare gradualmente a 3 tazze al di&#8217; a pieno regime, dando cosi&#8217; tempo al corpo di regire bene a questa nuova stimolazione disintossicante.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<ul>\n<li>Carciofo<\/li>\n<li>Rabarbaro<\/li>\n<li>Rosmarino<\/li>\n<li>Boldo<\/li>\n<li>Cicoria<\/li>\n<li>Liquirizia<\/li>\n<li>Camomilla<\/li>\n<li>Menta<\/li>\n<\/ul>\n<p>La miscele viene preparata partendo dalle singole erbe officinali, solo nel momento in cui riceviamo l&#8217;ordine.<\/p>\n<p>Per questo motivo e&#8217; sempre fresca di preparazione.<\/p>\n<p>Per informazione sul consumo, considerate che con 3 tazze al giorno, in una settimana consumate circa 100 grammi di miscela.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tisana di erbe officinali n.5E &#8211; depurazione del fegato, digestiva 100g Miscela d&#8217;erbe officinali particolarmente studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. E&#8217; una classica formulazione epatica, di sapore piuttosto amarotico adatta anche a chiunque desideri effettuare&#8230;<\/p>\n","protected":false},"featured_media":50903,"template":"","meta":{"_acf_changed":false},"product_brand":[9605],"product_cat":[45114],"product_tag":[10772,13503,10730,10952,11362,11173],"giftcard-category":[],"class_list":{"0":"post-57518","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erboristeria-demetra-www-erboristerie-com","7":"product_cat-te-infusi-e-tisane-sfusi","8":"product_tag-derbe-2","9":"product_tag-epatica","10":"product_tag-fegato","11":"product_tag-gr","12":"product_tag-officinali","13":"product_tag-tisana","14":"pa_formato-100-grammi","15":"pa_linea-tisane","16":"pa_marca-erboristeria-demetra-oderzo","17":"pa_tipologia-tisana","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T10:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/\",\"name\":\"Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"datePublished\":\"2008-05-06T14:06:57+00:00\",\"dateModified\":\"2025-09-15T10:15:12+00:00\",\"description\":\"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"width\":350,\"height\":458,\"caption\":\"Erbe officinali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Miscela di erbe officinali n.5E &#8211; depurazione del fegato, digestiva 100g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra","description":"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/","og_locale":"en_US","og_type":"article","og_title":"Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra","og_description":"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-15T10:15:12+00:00","og_image":[{"width":350,"height":458,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/","name":"Miscela di erbe officinali n.5E - depurazione del fegato, digestiva 100g - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","datePublished":"2008-05-06T14:06:57+00:00","dateModified":"2025-09-15T10:15:12+00:00","description":"Studiata per essere utilizzata come coadiuvante nei processi digestivi tramite la stimolazione della funzione epatica. Erboristeria Demetra","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","width":350,"height":458,"caption":"Erbe officinali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/miscela-di-erbe-officinali-n-5e-depurazione-del-fegato-digestiva-100g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Miscela di erbe officinali n.5E &#8211; depurazione del fegato, digestiva 100g"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/57518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/50903"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=57518"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=57518"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=57518"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=57518"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=57518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}