{"id":55502,"date":"2008-03-14T09:50:17","date_gmt":"2008-03-14T08:50:17","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=55502"},"modified":"2025-10-10T11:31:04","modified_gmt":"2025-10-10T09:31:04","slug":"purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/","title":{"rendered":"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio"},"content":{"rendered":"<p>Chicchi di purissima <strong>liquirizia Spezzatina Amarelli<\/strong> senza aromi conservanti e coloranti.<\/p>\n<p><strong>Confezione<\/strong>: sacchettino sigillato da 100 grammi<\/p>\n<p>Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.<\/p>\n<p>Ideali da sciogliere in bocca o da utilizzare per la preparazione del <strong>Liquore alla liquirizia<\/strong> che, con la liquirizia pura Spezzata o Spezzatina, risultera&#8217; piu&#8217;\u00a0intenso e unico e con le Favette alla Menta o i Rombetti all&#8217;Anice, invece, risulter\u00e0 leggermente pi\u00f9 aromatico<\/p>\n<p>La preparazione del liquore e&#8217; semplice e veloce e con la nostra ricetta fornita gratuitamente assieme a questo articolo, non potrete sbagliare. Otterrete circa 1,5 litri di liquore ogni 100g di liquirizia.<\/p>\n<p>La bella figura con i vostri amici e parenti e&#8217; assicurata!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chicchi di purissima liquirizia Spezzatina Amarelli senza aromi conservanti e coloranti. Confezione: sacchettino sigillato da 100 grammi Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica. Ideali da sciogliere in bocca o da utilizzare per&#8230;<\/p>\n","protected":false},"featured_media":55503,"template":"","meta":{"_acf_changed":false},"product_brand":[9632],"product_cat":[9711],"product_tag":[12207,11443,12209,11824,12206,12799],"giftcard-category":[],"class_list":{"0":"post-55502","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-amarelli","7":"product_cat-alimenti-vari","8":"product_tag-amarelli-2","9":"product_tag-liquirizia","10":"product_tag-liquore","11":"product_tag-omaggio","12":"product_tag-ricetta","13":"product_tag-spezzatina","14":"pa_formato-100-grammi","15":"pa_linea-amarelli","16":"pa_marca-amarelli","17":"pa_tipologia-caramelle","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T09:31:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"490\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/\",\"name\":\"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg\",\"datePublished\":\"2008-03-14T08:50:17+00:00\",\"dateModified\":\"2025-10-10T09:31:04+00:00\",\"description\":\"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg\",\"width\":\"490\",\"height\":\"400\",\"caption\":\"AMARELLI LIQUIRIZIA GR 100 SPEZZATINA + RICETTA LIQUORE OMAGGIO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra","description":"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/","og_locale":"en_US","og_type":"article","og_title":"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra","og_description":"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-10-10T09:31:04+00:00","og_image":[{"width":490,"height":400,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/","name":"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg","datePublished":"2008-03-14T08:50:17+00:00","dateModified":"2025-10-10T09:31:04+00:00","description":"Amarelli \u00e8 la liquirizia migliore e pi\u00f9 famosa al mondo come certificato dal recente riconoscimento ricevuto dalla storica fabbrica.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00002990.jpg","width":"490","height":"400","caption":"AMARELLI LIQUIRIZIA GR 100 SPEZZATINA + RICETTA LIQUORE OMAGGIO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/purissima-liquirizia-spezzatina-amarelli-100gr-ricetta-liquore-omaggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Purissima Liquirizia Spezzatina Amarelli 100gr + ricetta liquore omaggio"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/55502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/55503"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=55502"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=55502"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=55502"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=55502"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=55502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}