{"id":52758,"date":"2008-05-09T12:45:11","date_gmt":"2008-05-09T10:45:11","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=52758"},"modified":"2025-02-21T10:52:30","modified_gmt":"2025-02-21T09:52:30","slug":"santoreggia-biologica-foglie-satureja-montana","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/","title":{"rendered":"Santoreggia Biologica foglie (Satureja montana)"},"content":{"rendered":"<p><strong>Foglie in taglio tisana di Santoreggia (Satureja montana) BIOLOGICA<\/strong><\/p>\n<p data-start=\"56\" data-end=\"509\">Le foglie di Santoreggia (Satureja montana) sono note per le loro propriet\u00e0 digestive, toniche e antisettiche.<\/p>\n<p data-start=\"56\" data-end=\"509\">Questa pianta aromatica, dal sapore intenso e leggermente piccante, \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.<\/p>\n<p data-start=\"56\" data-end=\"509\">Grazie alla sua origine biologica, il prodotto \u00e8 privo di pesticidi e sostanze chimiche, garantendo la massima purezza e qualit\u00e0.<\/p>\n<p data-start=\"511\" data-end=\"865\">Oltre al suo effetto benefico sul sistema digerente, la Santoreggia \u00e8 apprezzata anche per le sue propriet\u00e0 stimolanti ed energizzanti.<\/p>\n<p data-start=\"511\" data-end=\"865\">Il suo infuso \u00e8 utile nei periodi di stanchezza fisica e mentale, favorendo la vitalit\u00e0 dell\u2019organismo.<\/p>\n<p data-start=\"511\" data-end=\"865\">Inoltre, la sua azione antisettica e balsamica la rende un valido aiuto per il benessere delle vie respiratorie.<\/p>\n<p data-start=\"867\" data-end=\"1172\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"867\" data-end=\"885\">Modalit\u00e0 d\u2019uso<\/strong><\/p>\n<p data-start=\"867\" data-end=\"1172\" data-is-last-node=\"\" data-is-only-node=\"\">Aggiungere un cucchiaino di foglie in una tazza di acqua bollente e lasciare in infusione per 5-10 minuti.<\/p>\n<p data-start=\"867\" data-end=\"1172\" data-is-last-node=\"\" data-is-only-node=\"\">Filtrare e bere dopo i pasti per favorire la digestione o durante la giornata per un effetto tonico e rinvigorente.<\/p>\n<p data-start=\"867\" data-end=\"1172\" data-is-last-node=\"\" data-is-only-node=\"\">Ottima anche come tisana balsamica nelle stagioni pi\u00f9 fredde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foglie in taglio tisana di Santoreggia (Satureja montana) BIOLOGICA Le foglie di Santoreggia (Satureja montana) sono note per le loro propriet\u00e0 digestive, toniche e antisettiche. Questa pianta aromatica, dal sapore intenso e leggermente piccante, \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale&#8230;<\/p>\n","protected":false},"featured_media":50903,"template":"","meta":{"_acf_changed":false},"product_brand":[9617],"product_cat":[10075],"product_tag":[19605,20644,21103,11703,18999,11701],"giftcard-category":[],"class_list":{"0":"post-52758","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbamea","7":"product_cat-erbe-r-s","8":"product_tag-bio-2","9":"product_tag-foglie-2","10":"product_tag-gr-2","11":"product_tag-montana","12":"product_tag-santoreggia-2","13":"product_tag-satureja","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T09:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/\",\"name\":\"Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"datePublished\":\"2008-05-09T10:45:11+00:00\",\"dateModified\":\"2025-02-21T09:52:30+00:00\",\"description\":\"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg\",\"width\":350,\"height\":458,\"caption\":\"Erbe officinali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santoreggia Biologica foglie (Satureja montana)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra","description":"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/","og_locale":"en_US","og_type":"article","og_title":"Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra","og_description":"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-02-21T09:52:30+00:00","og_image":[{"width":350,"height":458,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/","name":"Santoreggia Biologica foglie (Satureja montana) - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","datePublished":"2008-05-09T10:45:11+00:00","dateModified":"2025-02-21T09:52:30+00:00","description":"La Santoreggia \u00e8 utilizzata tradizionalmente per stimolare la digestione, contrastare la fermentazione intestinale e favorire il benessere gastrointestinale.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/01\/products-00001716.jpg","width":350,"height":458,"caption":"Erbe officinali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/santoreggia-biologica-foglie-satureja-montana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Santoreggia Biologica foglie (Satureja montana)"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/52758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/50903"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=52758"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=52758"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=52758"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=52758"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=52758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}