{"id":51422,"date":"2008-05-09T12:45:01","date_gmt":"2008-05-09T10:45:01","guid":{"rendered":"http:\/\/www.erboristerie.com\/?post_type=product&#038;p=51422"},"modified":"2025-04-05T21:11:29","modified_gmt":"2025-04-05T19:11:29","slug":"biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/","title":{"rendered":"BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli"},"content":{"rendered":"<p><strong>BioKap Anticaduta Shampoo Rinforzante 200ml &#8211; Biosline<\/strong><\/p>\n<p>A base di Tricofoltil\u00ae, Olax dissitiflora e Saw palmetto per irrobustire e rafforzare i capelli<\/p>\n<p>BioKap\u00ae Anticaduta Shampoo Rinforzante \u00e8 uno specifico trattamento cosmetico arricchito con Tricofoltil\u00ae (complesso a base di Olio di Lino, Rame e Biotina), Olax dissitiflora e Saw Palmetto per rafforzare e irrobustire i capelli.<\/p>\n<p>Gli estratti di Achillea, Luppolo e Malva svolgono un\u2019azione idratante completata dalla specifica azione rinfrescante del Mentolo e degli Oli essenziali di Rosmarino bio e Melaleuca alternifolia bio.<\/p>\n<p>L\u2019estratto di Ortica esercita un\u2019azione sebonormalizzante. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.<\/p>\n<p><strong>Quando usarlo<\/strong><\/p>\n<p>Indicato in caso di eccessiva caduta di capelli.<\/p>\n<p><strong>Come usarlo<\/strong><\/p>\n<p>Applicare una noce di prodotto sui capelli bagnati, massaggiare e sciacquare.<\/p>\n<p><strong>Cosa contiene<\/strong><\/p>\n<p>Tricofoltil\u00ae\u00a0 (complesso a base di Olio di Lino, Rame e Biotina), Aloe Vera gel bio, estratti di Olax dissitiflora, China, Capsico, Achillea, Ortica, semi di Zucca, Saw palmetto, Luppolo, Malva, Mentolo, o.e. di Rosmarino bio e o.e. Melaleuca bio.<\/p>\n<p><strong>Le Garanzie BioKap\u00ae<\/strong><\/p>\n<p>senza Peg<br \/>\nsenza Siliconi<br \/>\nsenza Parabeni<br \/>\nsenza SLES<br \/>\nNickel Tested<br \/>\nDermatologicamente testato.<\/p>\n<p><strong>INCI<\/strong><\/p>\n<p>aqua\/water, sodium coco-sulfate, aloe barbadensis leaf juice*, coco-glucoside, glycerin, cocamidopropyl betaine, cocodimonium hydroxypropyl hydrolyzed wheat protein, lactic acid, glyceryl oleate, disodium cocoyl glutamate, hydrolyzed wheat protein, menthol, parfum\/fragrance, sodium chloride, sodium benzoate, potassium sorbate, sodium cocoyl glutamate, sasa kurilensis leaf\/stem extract*,\u00a0 alcohol, linum usitatissimum seed oil\/ linum usitatissimum (linseed) seed oil, olax dissitiflora extract, capsicum annuum extract, mentha arvensis leaf oil, mentha viridis leaf oil\/ mentha viridis (spearmint) leaf oil, leuconostoc\/radish root ferment filtrate, citric acid,\u00a0 limonene, humulus lupulus extract\/humulus lupulus (hops) extract, malva sylvestris flower\/leaf extract\/malva sylvestris (mallow) flower\/leaf extract, aesculus hippocastanum seed extract\/aesculus hippocastanum (horse chestnut) seed extract, cinchona succirubra bark extract, urtica dioica leaf extract\/urtica dioica (nettle) leaf extract, carvone, citrus limon peel oil\/citrus limon (lemon) peel oil, copper acetylmethionate, betula alba leaf extract, biotin,\u00a0 serenoa serrulata fruit extract, citrus aurantium bergamia leaf oil\/ citrus aurantium bergamia (bergamot) leaf oil, achillea millefolium extract,\u00a0 melaleuca alternifolia leaf oil*\/melaleuca alternifolia (tea tree) leaf oil*, rosmarinus officinalis leaf oil*\/ rosmarinus officinalis (rosemary) leaf oil*, cucurbita pepo seed extract\/ cucurbita pepo (pumpkin) seed extract.<br \/>\n*da agricoltura biologica\/ from organic farming<br \/>\nLa lista degli ingredienti pu\u00f2 subire delle leggere modifiche, fai riferimento a quella riportata sulla confezione del prodotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BioKap Anticaduta Shampoo Rinforzante 200ml &#8211; Biosline A base di Tricofoltil\u00ae, Olax dissitiflora e Saw palmetto per irrobustire e rafforzare i capelli BioKap\u00ae Anticaduta Shampoo Rinforzante \u00e8 uno specifico trattamento cosmetico arricchito con Tricofoltil\u00ae (complesso a base di Olio di Lino, Rame e Biotina), Olax&#8230;<\/p>\n","protected":false},"featured_media":112344,"template":"","meta":{"_acf_changed":false},"product_brand":[9595],"product_cat":[10307,45044],"product_tag":[10917,10920,10919,10918,19456],"giftcard-category":[],"class_list":{"0":"post-51422","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-biosline","7":"product_cat-capelli","8":"product_cat-detergenza","9":"product_tag-200ml","10":"product_tag-anticaduta","11":"product_tag-biokap","12":"product_tag-rinforzante","13":"product_tag-shampoo-2","14":"pa_linea-profumazione-biokap","15":"pa_tipologia-shampoo","17":"first","18":"instock","19":"sale","20":"purchasable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-05T19:11:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/\",\"name\":\"Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg\",\"datePublished\":\"2008-05-09T10:45:01+00:00\",\"dateModified\":\"2025-04-05T19:11:29+00:00\",\"description\":\"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"APIXefferv 003\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra","description":"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/","og_locale":"en_US","og_type":"article","og_title":"Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra","og_description":"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-04-05T19:11:29+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/","name":"Problemi di caduta: BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg","datePublished":"2008-05-09T10:45:01+00:00","dateModified":"2025-04-05T19:11:29+00:00","description":"per irrobustire e rafforzare i capelli. La sua formula \u00e8 completata dal gel di Aloe Vera bio, che svolge un\u2019azione protettiva sul cuoio capelluto.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2008\/05\/00001322.jpg","width":1200,"height":1200,"caption":"APIXefferv 003"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/biokap-anticaduta-shampoo-rinforzante-200ml-per-rafforzare-e-irrobustire-i-capelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"BioKap Anticaduta Shampoo Rinforzante 200ml per rafforzare e irrobustire i capelli"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/51422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/112344"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=51422"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=51422"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=51422"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=51422"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=51422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}