{"id":132590,"date":"2013-05-13T17:56:35","date_gmt":"2013-05-13T15:56:35","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=132590"},"modified":"2026-01-30T12:50:18","modified_gmt":"2026-01-30T11:50:18","slug":"potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/","title":{"rendered":"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini"},"content":{"rendered":"<p><strong>Potassio ascorbato 180 pastiglie &#8211; dr. Giorgini<\/strong><\/p>\n<p>Disponibile anche nel formato da 60 pastiglie<\/p>\n<p>Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.<\/p>\n<p>La vitamina C possiede molteplici propriet\u00e0: favorisce il metabolismo energetico riducendo la stanchezza e l\u2019affaticamento; protegge le cellule dallo stress ossidativo e rigenera la forma ridotta della vitamina E; contribuisce alla normale funzione del sistema immunitario, del sistema nervoso e alla funzione psicologica; promuove la formazione del collagene aiutando a mantenere le normali funzioni di vasi sanguigni, ossa, cartilagini, pelle, denti e gengive; incrementa l\u2019assorbimento del ferro.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione da 1 a 5 pastiglie una volta al giorno in qualunque momento. Richiudere accuratamente dopo l&#8217;utilizzo.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Potassio ascorbato, cellulosa microcristallina\u00b0, gomma arabica\u00b0, ribosio, silicio biossido\u00b0\u00b0, magnesio stearato di origine vegetale\u00b0\u00b0.<br \/>\n\u00b0Agente di carica. \u00b0\u00b0Antiagglomerante.<\/p>\n<p>Per la<strong> tabella nutrizionale<\/strong> fai riferimento alle immagini del prodotto.<\/p>\n<p><strong>Non contiene conservanti, coloranti, aromi ed edulcoranti di sintesi.<\/strong><\/p>\n<p><strong>Prodotto adatto ai vegani.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potassio ascorbato 180 pastiglie &#8211; dr. Giorgini Disponibile anche nel formato da 60 pastiglie Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio. La vitamina C possiede molteplici propriet\u00e0: favorisce il metabolismo energetico riducendo la stanchezza&#8230;<\/p>\n","protected":false},"featured_media":119243,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[46275,10163],"product_tag":[20849,14699,19297],"giftcard-category":[],"class_list":{"0":"post-132590","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-dr-vitamine","8":"product_cat-linea-oro-classica","9":"product_tag-ascorbato-2","10":"product_tag-pastiglie","11":"product_tag-potassio-2","12":"pa_formato-60-pastiglie","13":"pa_linea-linea-oro","14":"pa_marca-dr-giorgini","15":"pa_tipologia-compresse","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:50:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/\",\"name\":\"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg\",\"datePublished\":\"2013-05-13T15:56:35+00:00\",\"dateModified\":\"2026-01-30T11:50:18+00:00\",\"description\":\"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra","description":"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/","og_locale":"en_US","og_type":"article","og_title":"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra","og_description":"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:50:18+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/","name":"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg","datePublished":"2013-05-13T15:56:35+00:00","dateModified":"2026-01-30T11:50:18+00:00","description":"Integratore alimentare a base di potassio ascorbato, forma alcalina e non acida della vitamina C, arricchito con ribosio.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00009819-potassio-ascorbato-180.jpeg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/potassio-ascorbato-180-pastiglie-protegge-dallo-stress-ossidativo-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Potassio ascorbato 180 pastiglie protegge dallo stress ossidativo dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/132590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/119243"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=132590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=132590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=132590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=132590"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=132590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}