{"id":130556,"date":"2025-06-26T18:10:51","date_gmt":"2025-06-26T16:10:51","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=130556"},"modified":"2026-01-30T12:48:42","modified_gmt":"2026-01-30T11:48:42","slug":"acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/","title":{"rendered":"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini"},"content":{"rendered":"<p><strong>Acciaiovis 60 pastiglie &#8211; dr. Giorgini<\/strong><\/p>\n<p>(Disponibile anche nel formato da 180 pastiglie oltre alla versione liquida da 200ml e 500ml)<\/p>\n<p>Integratore alimentare a base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.<\/p>\n<p>In particolare, il ferro favorisce la sintesi dell\u2019emoglobina, il trasporto dell\u2019ossigeno nei tessuti dell\u2019organismo e, insieme alle vitamine B6 e B12, promuove la formazione dei globuli rossi.<\/p>\n<p>La vitamina C accresce l\u2019assorbimento del ferro, il rame ne promuove il trasporto nell\u2019organismo mentre le vitamine A e B2 ne regolano il metabolismo.<\/p>\n<p>Inoltre, l\u2019acido folico contribuisce alla crescita dei tessuti materni in gravidanza e coadiuva l\u2019emopoiesi, cio\u00e8 la sintesi di tutte le cellule del sangue.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 4 pastiglie una o due volte al giorno in qualunque momento (da 4 a 8 pastiglie al giorno).<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Romice (Rumex crispus) radici E.I.S., calcio fosfato bibasico, magnesio glicerofosfato, cellulosa microcristallina\u00b0, gomma arabica\u00b0, citrato ferrico di ammonio, acerola (Malpighia glabra) frutti E.S. (titolato al 50% in vitamina C), rosa canina (Rosa canina) frutti E.S. (titolato al 70% in vitamina C), zinco gluconato, camu-camu (Myrciaria dubia) frutti E.S. (titolato al 50% in vitamina C), silicio biossido\u00b0\u00b0, angelica silvestre (Angelica sylvestris) radici E.I.S., anice verde (Pimpinella anisum) frutti E.I.S., carvi o cumino dei prati (Carum carvi) frutti E.I.S., crescione (Nasturtium officinale) erba E.I.S., cuscuta (Cuscuta epithymum) erba E.I.S., equiseto o coda cavallina (Equisetum arvense) erba E.I.S., fieno greco (Trigonella foenum-graecum) semi E.I.S., finocchio (Foeniculum vulgare) frutti E.I.S., genziana (Gentiana lutea) radici E.I.S., magnesio ossido, vitamina E di origine naturale (acetato di D-\u03b1-tocoferile), manganese gluconato, vitamina B3 (nicotinamide), magnesio stearato di origine vegetale\u00b0\u00b0, vitamina B5 (pantotenato di calcio), sodio borato, vitamina B6 (piridossina cloridrato), rame gluconato, vitamina A (acetato di retinile), vitamina D3 (colecalciferolo) di origine vegetale (estratta da lichene Cladonia rangiferina), vitamina K1 (fillochinone), vitamina B1 (tiamina cloridrato), vitamina B2 (riboflavina), vitamina B12 (cianocobalamina), cromo picolinato, acido folico, potassio ioduro, biotina, sodio molibdato, sodio selenito.<br \/>\n\u00b0Agente di carica. \u00b0\u00b0Antiagglomerante.<br \/>\nE.S.= Estratto secco. E.I.S.= Estratto integrale secco. NRV= Valore nutritivo di riferimento.<\/p>\n<p>Naturale caratteristica distintiva: odore caratteristico<\/p>\n<p><strong>Prodotto adatto ai vegani.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acciaiovis 60 pastiglie &#8211; dr. Giorgini (Disponibile anche nel formato da 180 pastiglie oltre alla versione liquida da 200ml e 500ml) Integratore alimentare a base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale. In particolare,&#8230;<\/p>\n","protected":false},"featured_media":118005,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[10163,49558],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-130556","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-linea-oro-classica","8":"product_cat-sport","9":"pa_formato-60-pastiglie","10":"pa_linea-linea-oro","11":"pa_marca-dr-giorgini","12":"pa_tipologia-compresse","14":"first","15":"instock","16":"sale","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:48:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/\",\"name\":\"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg\",\"datePublished\":\"2025-06-26T16:10:51+00:00\",\"dateModified\":\"2026-01-30T11:48:42+00:00\",\"description\":\"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra","description":"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/","og_locale":"en_US","og_type":"article","og_title":"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra","og_description":"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:48:42+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/","name":"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg","datePublished":"2025-06-26T16:10:51+00:00","dateModified":"2026-01-30T11:48:42+00:00","description":"A base di erbe, sali minerali e vitamine; particolarmente utile durante la gravidanza o in caso di accresciuto fabbisogno nutrizionale.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2013\/05\/00007126.jpeg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/acciaiovis-60-pastiglie-ricco-in-ferro-vitamine-e-minerali-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Acciaiovis\u00a060 pastiglie ricco in ferro, vitamine e minerali dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/130556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/118005"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=130556"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=130556"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=130556"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=130556"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=130556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}