{"id":126182,"date":"2024-06-01T18:22:03","date_gmt":"2024-06-01T16:22:03","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=126182"},"modified":"2025-09-10T18:54:57","modified_gmt":"2025-09-10T16:54:57","slug":"shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/","title":{"rendered":"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia &#8211; L&#8217;Erbolario"},"content":{"rendered":"<p><strong>Shampoo Solido con Pistacchio di Sicilia &#8211; Erbolario<\/strong><\/p>\n<p>Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli.<\/p>\n<p>Basta bagnare il panetto e massaggiarlo tra le mani fino a creare una morbida schiuma oppure passarlo direttamente su corpo e capelli bagnati, per poi risciacquare con cura.<\/p>\n<p><strong>Modo d&#8217;uso<\/strong><\/p>\n<p>Modo d&#8217;uso: Massaggiare il panetto tra le mani per creare una morbida schiuma oppure passarlo direttamente sul corpo e sui capelli inumiditi, quindi risciacquare abbondantemente. Se necessario ripetere l\u2019operazione.<\/p>\n<p><strong>Cosa sapere in pi\u00f9<\/strong><\/p>\n<p>Panetto da 60g<\/p>\n<p>Non testato su animali: certificato ICEA. Testato al Nickel e 7 metalli pesanti<\/p>\n<p><a href=\"https:\/\/www.erboristerie.com\/it\/tutti-i-prodotti\/?s=pistacchio&amp;post_type=product&amp;filter_linea-profumazione=pistacchio&amp;type_aws=true\">Clicca qui per gli altri prodotti della linea Pistacchio Erbolario<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shampoo Solido con Pistacchio di Sicilia &#8211; Erbolario Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli. Basta bagnare il panetto e massaggiarlo tra le mani fino a creare una morbida&#8230;<\/p>\n","protected":false},"featured_media":126136,"template":"","meta":{"_acf_changed":false},"product_brand":[9603],"product_cat":[49195,10307,45044],"product_tag":[11435,11030,10650,11433,11031,11033,11434],"giftcard-category":[],"class_list":{"0":"post-126182","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbolario","7":"product_cat-linee-profumate","8":"product_cat-capelli","9":"product_cat-detergenza","10":"product_tag-30ml","11":"product_tag-bardana","12":"product_tag-crema","13":"product_tag-impure","14":"product_tag-pelli","15":"product_tag-rosmarino","16":"product_tag-rosmarino30ml","17":"pa_formato-60-grammi","18":"pa_linea-profumazione-pistacchio","19":"pa_marca-lerbolario","20":"pa_tipologia-shampoo","22":"first","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L&#039;Erbolario - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L&#039;Erbolario - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T16:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/\",\"name\":\"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L'Erbolario - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg\",\"datePublished\":\"2024-06-01T16:22:03+00:00\",\"dateModified\":\"2025-09-10T16:54:57+00:00\",\"description\":\"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia &#8211; L&#8217;Erbolario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L'Erbolario - Erboristeria Demetra","description":"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/","og_locale":"en_US","og_type":"article","og_title":"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L'Erbolario - Erboristeria Demetra","og_description":"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-09-10T16:54:57+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/","name":"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia - L'Erbolario - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg","datePublished":"2024-06-01T16:22:03+00:00","dateModified":"2025-09-10T16:54:57+00:00","description":"Questo pratico cosmetico due in uno dal profumo delicatamente gourmand consente con un semplice gesto una detersione super piacevole di corpo e capelli","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2024\/05\/00011523-pistacchio-shampoo-solido-erbolario-erboristerie-com.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/shampoo-solido-con-olio-ed-estratto-di-pistacchio-di-sicilia-lerbolario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Shampoo Solido con olio ed estratto di Pistacchio di Sicilia &#8211; L&#8217;Erbolario"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/126182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/126136"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=126182"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=126182"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=126182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=126182"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=126182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}