{"id":114410,"date":"2022-02-25T18:24:10","date_gmt":"2022-02-25T17:24:10","guid":{"rendered":"https:\/\/www.erboristerie.com\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/"},"modified":"2025-10-21T16:32:05","modified_gmt":"2025-10-21T14:32:05","slug":"cannella-foglie-olio-essenziale-10ml-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/","title":{"rendered":"Cannella foglie olio essenziale 10ml dr.Giorgini"},"content":{"rendered":"<p>Tutti gli oli essenziali Giorgini Dr. Martino vengono potenziati con un antico metodo, chiamato di \u201cvivificazione\u201d.<\/p>\n<p>Il processo di \u201cvivificazione\u201d si realizzamettendo a contatto l\u2019olio essenziale con il sale estratto dalle ceneri di vegetali bruciati e calcinati.<\/p>\n<p>Oli essenziali Giorgini Dr. Martino sono 100% naturali realizzati per distillazione in corrente di vapore da piante aromatiche o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.<\/p>\n<p><strong> Modo d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 1 &#8211; 2 gocce al giorno di olio essenziale da diluire in un alimento a piacere o in una bottiglia d\u2019acqua da consumare nell\u2019arco della giornata (agitare bene prima di bere).<\/p>\n<p>\u00c8 possibile l\u2019uso esterno per massaggi rilassanti diluendo opportunamente in una base emolliente come una crema o, ancora meglio, un olio vegetale, oppure aggiungere alcune gocce nei diffusori per aromi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti gli oli essenziali Giorgini Dr. Martino vengono potenziati con un antico metodo, chiamato di \u201cvivificazione\u201d. Il processo di \u201cvivificazione\u201d si realizzamettendo a contatto l\u2019olio essenziale con il sale estratto dalle ceneri di vegetali bruciati e calcinati. Oli essenziali Giorgini Dr. Martino sono 100% naturali&#8230;<\/p>\n","protected":false},"featured_media":122557,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[10187],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-114410","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-oli-essenziali-vivificati","8":"pa_formato-10-ml","9":"pa_linea-o-e-v-oli-essenziali-vivificati","10":"pa_marca-dr-giorgini","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T14:32:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/\",\"name\":\"Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg\",\"datePublished\":\"2022-02-25T17:24:10+00:00\",\"dateModified\":\"2025-10-21T14:32:05+00:00\",\"description\":\"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cannella foglie olio essenziale 10ml dr.Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra","description":"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/","og_locale":"en_US","og_type":"article","og_title":"Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra","og_description":"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2025-10-21T14:32:05+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/","name":"Cannella foglie olio essenziale 10ml dr.Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg","datePublished":"2022-02-25T17:24:10+00:00","dateModified":"2025-10-21T14:32:05+00:00","description":"Oli essenziali 100% naturali estratti per distillazione in corrente di vapore o, nel caso degli agrumi, per spremitura a freddo delle scorze dei frutti.","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2022\/02\/00009572_cannella_foglie_olio_essenziale_giorgini.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/cannella-foglie-olio-essenziale-10ml-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Cannella foglie olio essenziale 10ml dr.Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/114410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/122557"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=114410"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=114410"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=114410"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=114410"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=114410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}