{"id":108173,"date":"2020-12-01T18:37:11","date_gmt":"2020-12-01T17:37:11","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=108173"},"modified":"2026-01-30T12:38:26","modified_gmt":"2026-01-30T11:38:26","slug":"pappa-reale-e-propoli-200ml-analcolico-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/","title":{"rendered":"Pappa reale e Propoli 200ml analcolico Dr.Giorgini"},"content":{"rendered":"<p><strong>PAPPA REALE E PROPOLI liquido analcoolico 200ml &#8211; Dr.Giorgini<\/strong><br \/>\nIntegratore di propoli e pappa reale fresca.<\/p>\n<p>Il propoli (chiamata anche &#8220;la&#8221; propoli) \u00e8 una sostanza complessa di origine vegetale che le api raccolgono e rielaborano con l\u2019aggiunta di cera, polline ed enzimi.<\/p>\n<p>La pappa reale, invece, rappresenta un \u201csuperalimento\u201d altamente nutritivo prodotto ed utilizzato dalle api stesse per nutrire le larve fino a tre giorni di et\u00e0 nonch\u00e9 l\u2019ape regina per tutta la durata della sua lunga vita.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><br \/>\nSi consiglia l\u2019assunzione delle dosi riportate di seguito, una o due volte al giorno in qualunque momento:<br \/>\n\u2022 1,4 ml per bambini da 1 a 3 anni;<br \/>\n\u2022 3,5 ml per bambini da 4 a 6 anni;<br \/>\n\u2022 5 ml per bambini da 7 a 10 anni;<br \/>\n\u2022 10 ml per adulti.<br \/>\nAssumere il prodotto puro o diluirlo in acqua.<br \/>\nSe desiderato, le due dosi possono essere assunte anche in un\u2019unica soluzione. Agitare prima dell\u2019uso. Misurino graduato incluso nella confezione. Conservare il prodotto fuori dal frigorifero anche dopo l&#8217;apertura.<\/p>\n<p><strong>Ingredienti<\/strong><br \/>\nGlicerina vegetale bidistillata, acqua pura, propoli (Propolis) resina E.I.L., pappa reale fresca.<\/p>\n<p>Non contiene alcool, zuccheri aggiunti, conservanti, coloranti, aromi ed edulcoranti di sintesi.<br \/>\n<strong>Naturale caratteristica distintiva: sapore gradevole.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAPPA REALE E PROPOLI liquido analcoolico 200ml &#8211; Dr.Giorgini Integratore di propoli e pappa reale fresca. Il propoli (chiamata anche &#8220;la&#8221; propoli) \u00e8 una sostanza complessa di origine vegetale che le api raccolgono e rielaborano con l\u2019aggiunta di cera, polline ed enzimi. La pappa reale,&#8230;<\/p>\n","protected":false},"featured_media":108174,"template":"","meta":{"_acf_changed":false},"product_brand":[9598],"product_cat":[45112,10163,9863],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-108173","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dr-giorgini-martino-ser-vis","7":"product_cat-propoli","8":"product_cat-linea-oro-classica","9":"product_cat-energia-e-vitalita","10":"pa_formato-200-ml","11":"pa_linea-linea-oro","12":"pa_marca-dr-giorgini","13":"pa_tipologia-liquido-analcolico","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:38:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/\",\"name\":\"Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009\",\"datePublished\":\"2020-12-01T17:37:11+00:00\",\"dateModified\":\"2026-01-30T11:38:26+00:00\",\"description\":\"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pappa reale e Propoli 200ml analcolico Dr.Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra","description":"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/","og_locale":"en_US","og_type":"article","og_title":"Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra","og_description":"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-01-30T11:38:26+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/","name":"Pappa reale e Propoli 200ml analcolico Dr.Giorgini - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009","datePublished":"2020-12-01T17:37:11+00:00","dateModified":"2026-01-30T11:38:26+00:00","description":"Integratore di propoli e pappa reale fresca per tutti, adulti e bambini. Gradevole e facile da assumere. Nuova formulazione del Dr. Martino Giorgini","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/12\/00010926.jpg?v=1611516009","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/pappa-reale-e-propoli-200ml-analcolico-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Pappa reale e Propoli 200ml analcolico Dr.Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/108173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/108174"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=108173"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=108173"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=108173"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=108173"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=108173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}