{"id":107609,"date":"2020-10-20T19:53:29","date_gmt":"2020-10-20T17:53:29","guid":{"rendered":"https:\/\/www.erboristerie.com\/?post_type=product&#038;p=107609"},"modified":"2026-02-04T12:04:38","modified_gmt":"2026-02-04T11:04:38","slug":"artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea","status":"publish","type":"product","link":"https:\/\/www.erboristerie.com\/en\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/","title":{"rendered":"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea"},"content":{"rendered":"<p><strong>Artiglio del Diavolo Forte 36 capsule vegetali &#8211; Erbamea<\/strong><\/p>\n<p>A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare.<\/p>\n<p><strong>1 capsula vegetale contiene<\/strong>: Artiglio del Diavolo radice estratto secco (titolato al 20% in arpagosidi) 225 mg, per un apporto di ben 45 mg di arpagosidi con 1 capsula.<\/p>\n<p><strong>Modo d\u2019uso:<\/strong> 1 capsula dopo colazione e 1 capsula dopo pranzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artiglio del Diavolo Forte 36 capsule vegetali &#8211; Erbamea A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 1 capsula vegetale contiene: Artiglio del Diavolo radice estratto secco (titolato al 20% in arpagosidi) 225 mg, per&#8230;<\/p>\n","protected":false},"featured_media":107610,"template":"","meta":{"_acf_changed":false},"product_brand":[9617],"product_cat":[9827,49560],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-107609","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-erbamea","7":"product_cat-articolazioni","8":"product_cat-singoli-in-pastiglie","10":"first","11":"instock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra<\/title>\n<meta name=\"description\" content=\"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra\" \/>\n<meta property=\"og:description\" content=\"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/\" \/>\n<meta property=\"og:site_name\" content=\"Erboristeria Demetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erboristeria.demetra.online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T11:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/\",\"url\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/\",\"name\":\"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra\",\"isPartOf\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162\",\"datePublished\":\"2020-10-20T17:53:29+00:00\",\"dateModified\":\"2026-02-04T11:04:38+00:00\",\"description\":\"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162\",\"width\":560,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erboristerie.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All products\",\"item\":\"https:\/\/www.erboristerie.com\/en\/all-products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#website\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"name\":\"Erboristeria Demetra\",\"description\":\"Your natural health\",\"publisher\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#organization\",\"name\":\"Erboristeria Demetra\",\"url\":\"https:\/\/www.erboristerie.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"contentUrl\":\"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981\",\"width\":201,\"height\":54,\"caption\":\"Erboristeria Demetra\"},\"image\":{\"@id\":\"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/erboristeria.demetra.online\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra","description":"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/","og_locale":"en_US","og_type":"article","og_title":"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra","og_description":"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec","og_url":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/","og_site_name":"Erboristeria Demetra","article_publisher":"https:\/\/www.facebook.com\/erboristeria.demetra.online","article_modified_time":"2026-02-04T11:04:38+00:00","og_image":[{"width":560,"height":433,"url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/","url":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/","name":"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea - Erboristeria Demetra","isPartOf":{"@id":"https:\/\/www.erboristerie.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162","datePublished":"2020-10-20T17:53:29+00:00","dateModified":"2026-02-04T11:04:38+00:00","description":"A base di estratto secco di radice di Artiglio del diavolo utile per favorire la fisiologica funzionalit\u00e0 articolare. 2 capsule vegatali al d\u00ec","breadcrumb":{"@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#primaryimage","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2020\/10\/00010876.jpg?v=1611516162","width":560,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/www.erboristerie.com\/it\/prodotto\/artiglio-del-diavolo-forte-36-capsule-vegetali-erbamea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erboristerie.com\/en\/"},{"@type":"ListItem","position":2,"name":"All products","item":"https:\/\/www.erboristerie.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Artiglio del Diavolo Forte 36 capsule vegetali Erbamea"}]},{"@type":"WebSite","@id":"https:\/\/www.erboristerie.com\/it\/#website","url":"https:\/\/www.erboristerie.com\/it\/","name":"Erboristeria Demetra","description":"Your natural health","publisher":{"@id":"https:\/\/www.erboristerie.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erboristerie.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.erboristerie.com\/it\/#organization","name":"Erboristeria Demetra","url":"https:\/\/www.erboristerie.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","contentUrl":"https:\/\/www.erboristerie.com\/wp-content\/uploads\/2019\/11\/LOGO_ERBORISTERIA_DEMETRA_original.png?v=1611516981","width":201,"height":54,"caption":"Erboristeria Demetra"},"image":{"@id":"https:\/\/www.erboristerie.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erboristeria.demetra.online"]}]}},"_links":{"self":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product\/107609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media\/107610"}],"wp:attachment":[{"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/media?parent=107609"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_brand?post=107609"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_cat?post=107609"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/product_tag?post=107609"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.erboristerie.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=107609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}